{"id":52460,"date":"2016-07-13T14:06:19","date_gmt":"2016-07-13T17:06:19","guid":{"rendered":"http:\/\/www.hoymercedes.com.ar\/principal\/?p=52460"},"modified":"2016-07-13T14:06:19","modified_gmt":"2016-07-13T17:06:19","slug":"mercedes-y-comunicaciones-jugaran-sin-publico-por-tiempo-indeterminado","status":"publish","type":"post","link":"https:\/\/www.hoymercedes.com.ar\/principal\/2016\/07\/13\/mercedes-y-comunicaciones-jugaran-sin-publico-por-tiempo-indeterminado\/","title":{"rendered":"Mercedes y Comunicaciones jugar\u00e1n sin p\u00fablico por tiempo indeterminado"},"content":{"rendered":"<p><em><strong>Luego del partido que empataron el viernes 2 a 2 Club Mercedes y Comunicaciones, se desat\u00f3 una batahola entre ambas parcialidades fuera del estadio de la Liga Mercedina y entre lunes y martes se realizaron diferentes reuniones para determinar sanciones y pasos a seguir, ya sea a nivel seguridad como deportivo.<\/strong><\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"52461\" data-permalink=\"https:\/\/www.hoymercedes.com.ar\/principal\/2016\/07\/13\/mercedes-y-comunicaciones-jugaran-sin-publico-por-tiempo-indeterminado\/dscn0066\/#main\" data-orig-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2016\/07\/DSCN0066.jpg\" data-orig-size=\"650,487\" data-comments-opened=\"1\" data-image-title=\"DSCN0066\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2016\/07\/DSCN0066.jpg\" class=\"aligncenter size-medium wp-image-52461\" src=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2016\/07\/DSCN0066-630x472.jpg\" alt=\"DSCN0066\" width=\"630\" height=\"472\" srcset=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2016\/07\/DSCN0066-630x472.jpg 630w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2016\/07\/DSCN0066-150x112.jpg 150w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2016\/07\/DSCN0066.jpg 650w\" sizes=\"auto, (max-width: 630px) 100vw, 630px\" \/><\/p>\n<p>Esteban Marcelo, presidente de la Liga Mercedina de F\u00fatbol, dialog\u00f3 con el programa El Pulso, que se emite de lunes a viernes de 8 a 12 por FM La Tribuna 103.5 y manifest\u00f3 que \u00abfue una triste situaci\u00f3n que lo venimos manifestando en diferentes medios. Era algo que hab\u00eda quedado casi en el olvido. Uno que tiene muchos a\u00f1os de ir a la cancha, antes se daba como algo casi normal porque pasaba tres o cuatro veces por a\u00f1o pero con el trabajo de la Comisi\u00f3n Directiva y los clubes, se sum\u00f3 mucha gente a las tribunas, como en el caso de la gente de Trocha, el caso del a\u00f1o pasado con Juventud de Suipacha cuando lleg\u00f3 a las finales, Club Mercedes estaba llevando m\u00e1s gente que el a\u00f1o pasado y este a\u00f1o Comunicaciones y en el Federaci\u00f3n Norte, Quilmes tambi\u00e9n lo hizo. Hicimos un buen trabajo con buenos campeonatos y con mayor seguridad, y se lleg\u00f3 a esta situaci\u00f3n que nada tiene que ver con lo futbol\u00edstico, porque en la cancha no pas\u00f3 nada. Termin\u00f3 el partido 2 a 2 con un muy buen espect\u00e1culo y en la calle, pero con esto de que existen\u00a0algunos grupos min\u00fasculos a los que despu\u00e9s se les suma m\u00e1s gente, termin\u00f3 con un lamentable final, con personas lesionadas, autos da\u00f1ados y gener\u00f3 una complicaci\u00f3n en la que a partir de eso tuve una serie de reuniones y tomamos una serie de medidas\u00bb.<\/p>\n<p>Respecto a la seguridad planteada para el partido, Marcelo relat\u00f3 que \u00abhabitualmente pagamos cinco efectivos policiales. Para este encuentro, teniendo en cuenta que ten\u00edamos el comentario de que algo pod\u00eda suceder, superamos el doble de efectivos porque pagamos doce y adem\u00e1s la polic\u00eda en forma gratuita llev\u00f3 al Grupo de Apoyo Departamental y de la Polic\u00eda Local, que sumaban cerca de 20 efectivos. As\u00ed y todo, pas\u00f3 lo que pas\u00f3. Aparentemente, si bien se est\u00e1 definiendo, una persona abri\u00f3 en forma prematura un port\u00f3n que no ten\u00eda que abrir mientras sal\u00eda la gente de Comunicaciones y este grupo min\u00fasculo decidi\u00f3 ir a buscar a la parcialidad del Cartero y esta respondi\u00f3. Luego vino el accionar de la polic\u00eda que intent\u00f3 disuadir con gases lacrim\u00f3genos\u00bb.<\/p>\n<p>Tras los incidentes, fueron muchas las cosas que se dijeron y sobre esto reacci\u00f3n Marcelo: \u00abEn la reuni\u00f3n le dijimos a los delegados que uno trabaja en forma constante y es f\u00e1cil echarle la culpa al Presidente de la Liga y a la Comisi\u00f3n Directiva. El hincha tiene una pasi\u00f3n y te sorprende cuando algunos dichos son manifestados por los propios dirigentes que saben el trabajo que hacemos. Si llegamos a la situaci\u00f3n de que el f\u00fatbol creci\u00f3, es por un trabajo realizado y cuando pasan estas situaciones, cargan las tintas contra quienes no las tienen que cargar y no se hacen cargo de estas situaciones. Dirige mal un \u00e1rbitro, la culpa la tiene el Presidente de la Liga o la CD, cuando la realidad los \u00e1rbitros los eligen los mismos clubes cuando se les presentan los presupuestos a principio de a\u00f1o y encima saben qu\u00e9 es lo que eligen y luego cuestionan lo que ellos eligen. Pero es m\u00e1s f\u00e1cil echarle la culpa a la Liga. Cuando la cr\u00edtica viene de un hincha, sabemos que es pasional, pero cuando viene de un dirigente, duele m\u00e1s, porque ve el trabajo que hac\u00e9s y si uno se equivoca, bueno, pero cuando son injustas las cr\u00edticas, duelen\u00bb.<\/p>\n<p>\u00abEl que fue a la cancha el domingo ve que si hay dos tribunas llenas es porque hay mucho trabajo nuestro y de los clubes para que esto ocurra. Despu\u00e9s pasan otras situaciones que no se ven y que las seguimos luchando puertas adentro. Despu\u00e9s de lo que sucedi\u00f3, vamos a redoblar los esfuerzos para que no vuelva a ocurrir y para que no ganen los que no les gusta el f\u00fatbol\u00bb, a\u00f1adi\u00f3.<\/p>\n<p>Sobre las determinaciones (leer abajo), Marcelo coment\u00f3 que \u00abla Polic\u00eda se puso firme y determin\u00f3 que si alguien de Comunicaciones o Mercedes quiere entrar a la cancha a ver el partido, tendr\u00e1 sanciones contundentes. Si tenemos que tomar alguna medida extrema mayor, se lo har\u00e1. Tenemos el apoyo total de la Polic\u00eda y de los clubes. El Delegado de Trocha manifest\u00f3 que esto tendr\u00eda que salir en forma firme con el apoyo de toda la dirigencia de la Liga\u00bb.<\/p>\n<p>Por \u00faltimo, se le consult\u00f3 sobre la clasificaci\u00f3n de los equipos para los torneos regionales, tema que fue tratado a principio de a\u00f1o y que sigue siendo tema de consulta por los protagonistas de los clubes y Esteban Marcelo coment\u00f3 que el que acompa\u00f1e a Mercedes en el Federal C 2017 se conocer\u00e1 a fin de octubre o principios de noviembre cuando se termine la fase regular del Clausura y se obtenga al l\u00edder de la tabla general. En caso de que sea Mercedes, el segundo ser\u00e1 el clasificado.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Determinaciones de la LMF<\/strong><\/p>\n<p>En la Web oficial de la entidad, se dej\u00f3 de manifiesto lo sancionado tras las reuniones que hubo entre lunes y martes.<\/p>\n<p>&nbsp;<\/p>\n<p>La Comisi\u00f3n Directiva de la Liga Mercedina desea informar que a partir de los incidentes ocurridos el pasado viernes 8 de julio, al t\u00e9rmino del partido entre los equipos Mercedes y Comunicaciones y que ocasionaron vecinos lesionados y da\u00f1os en veh\u00edculos se llevaron distintas acciones:<\/p>\n<p><strong>1)<\/strong> El Tribunal de Disciplina abri\u00f3 un expediente de oficio para analizar la situaci\u00f3n y avanzar de acuerdo a lo que marca el Reglamento de Transgresiones y Penas del Consejo Federal.<\/p>\n<p><strong>2)<\/strong> Presidente y Vicepresidente de la Liga fueron invitados a una reuni\u00f3n el d\u00eda lunes, la cual se llev\u00f3 a cabo en la Municipalidad de Mercedes en la que tomaron participaci\u00f3n el titular de la Polic\u00eda Comunal, Comisario Sergio Macedo; la Secretaria de Control Urbano Josefina Kelly y el Jefe de Gabinete Municipal Ger\u00f3nimo Ustarroz.<\/p>\n<p><strong>3)<\/strong> El lunes por la noche, en la sede de la Liga se llev\u00f3 a cabo una reuni\u00f3n de la que tomaron parte dirigentes e invitados, de la mayor\u00eda de las distintas instituciones afiliadas.<\/p>\n<p><strong>4)<\/strong> El Presidente de la Liga fue invitado a una reuni\u00f3n celebrada en la tarde del martes en la Jefetaura Departamental de Polic\u00eda, donde estuvieron presentes el Segundo Jefe de dicha repartici\u00f3n y el titular de la Polic\u00eda Comunal.<\/p>\n<p><strong>5)<\/strong> Asimiso se toma conocimiento del inicio de una causa judicial que se tramita ante la Unidad Fiscal 5 del Departamento Judicial Mercedes.<\/p>\n<p>A partir de las reuniones mantenidas, la mesa directiva de la Liga Mercedina y con el acompa\u00f1amiento de los clubes afiliados ha decidido tomar una serie de medidas a saber:<\/p>\n<p><strong>a)<\/strong> Para el torneo de Primera Divisi\u00f3n, desde el pr\u00f3ximo fin de semana se proh\u00edbe -por tiempo indeterminado- la presencia de p\u00fablico perteneciente a los clubes Mercedes y Comunicaciones en cada uno de los partidos que deban jugar.<\/p>\n<p><strong>b)<\/strong> La mesa directiva dictaminar\u00e1 en forma conjunta con las autoridades policiales, -la posibilidad o no- sobre la presencia de p\u00fablico de los ocasiones rivales de los mencionados equipos en los partidos a jugarse.<\/p>\n<p><strong>c)<\/strong> La Polic\u00eda Comunal ha dictaminado que a partir de la fecha, los partidos que se cubr\u00edan con cinco efectivos policiales, ahora deber\u00e1n contar con la presencia de DIEZ uniformados, mientras que para los partidos considerados de alto riesgo el n\u00famero se elevar\u00e1 a VEINTE.<\/p>\n<p><strong>d)<\/strong> Que a partir de lo mencionado en el punto (c) la mesa directiva ha decidido confirmar s\u00f3lo la realizaci\u00f3n de la fecha a jugarse el pr\u00f3ximo fin de semana, quedando a resolver la continuidad o suspensi\u00f3n del certamen, de all\u00ed en adelante. Esto depender\u00e1 del an\u00e1lisis de los clubes afiliados y la situaci\u00f3n econ\u00f3mica a afrontar.<\/p>\n<p><strong>e)<\/strong> Para la divisi\u00f3n RESERVA, los partidos que deban jugar los clubes Mercedes y Comunicaciones se disputar\u00e1n a puertas cerradas, por tiempo indeterminado, o con p\u00fablico de los ocasiones rivales, en el caso de ser posible.<\/p>\n<p><strong>f)<\/strong> A la par de estas acciones, dirigentes de la Liga Mercedina contin\u00faan manteniendo comunicaciones y participando con reuniones a nivel regional a los fines de requerir cambios a nivel provincial sobre los gastos de seguridad deportiva que las instituciones deben afrontar en cada una de las jornadas.<\/p>\n<p><strong>g)<\/strong> Se adelanta que de cara a la fecha del pr\u00f3ximo fin de semana, el partido de Reserva entre Mercedes \u2013 Comunicaciones se disputar\u00e1 a puertas cerradas, mientras que por el certamen de Primera, el encuentro entre Trocha y Comunicaciones solo se disputar\u00e1 con p\u00fablico de Trocha e imparciales.<\/p>\n<p><strong>h)<\/strong> Finalmente, se informa que de manera personal se realizar\u00e1n otras indicaciones a las instituciones afiliadas a los fines de garantizar seguridad para el normal desarrollo de cada una de las jornadas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Luego del partido que empataron el viernes 2 a 2 Club Mercedes y Comunicaciones, se desat\u00f3 una batahola entre ambas &#8230; <a title=\"Mercedes y Comunicaciones jugar\u00e1n sin p\u00fablico por tiempo indeterminado\" class=\"read-more\" href=\"https:\/\/www.hoymercedes.com.ar\/principal\/2016\/07\/13\/mercedes-y-comunicaciones-jugaran-sin-publico-por-tiempo-indeterminado\/\" aria-label=\"Leer m\u00e1s sobre Mercedes y Comunicaciones jugar\u00e1n sin p\u00fablico por tiempo indeterminado\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":52461,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[21],"tags":[2253,3686,1901,10],"class_list":["post-52460","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes","tag-comunicaciones","tag-esteban-marcelo","tag-liga-mercedina","tag-mercedes","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"jetpack_publicize_connections":[],"wps_subtitle":"Esteban Marcelo, presidente de la LMF","jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2016\/07\/DSCN0066.jpg","_links":{"self":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/52460","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/comments?post=52460"}],"version-history":[{"count":0,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/52460\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media\/52461"}],"wp:attachment":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media?parent=52460"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/categories?post=52460"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/tags?post=52460"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}