{"id":54844,"date":"2016-09-19T16:22:58","date_gmt":"2016-09-19T19:22:58","guid":{"rendered":"http:\/\/www.hoymercedes.com.ar\/principal\/?p=54844"},"modified":"2016-09-19T16:22:58","modified_gmt":"2016-09-19T19:22:58","slug":"comunicacion-de-eden-ante-falsos-inspectores","status":"publish","type":"post","link":"https:\/\/www.hoymercedes.com.ar\/principal\/2016\/09\/19\/comunicacion-de-eden-ante-falsos-inspectores\/","title":{"rendered":"Comunicaci\u00f3n de EDEN ante falsos inspectores"},"content":{"rendered":"<p>\u00abAnte denuncias sobre personas que present\u00e1ndose falsamente en nombre de EDEN\u00a0pretenden ingresar a los domicilios de los usuarios argumentando la necesidad de realizar trabajos, inspecciones o verificaciones,\u00a0EDEN reitera que la empresa <strong>no\u00a0desarrolla ning\u00fan tipo de tarea t\u00e9cnica en el interior de las viviendas,<\/strong> raz\u00f3n por la cual, bajo ninguna circunstancia se debe permitir el\u00a0ingreso de estas personas.<\/p>\n<p>En caso de detectar alg\u00fan tipo de situaci\u00f3n irregular se recomienda dar aviso inmediato a la Polic\u00eda y\/o comunicarse a nuestro Centro de Atenci\u00f3n\u00a0Telef\u00f3nica las 24 horas \u00a00-800-999-3336.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abAnte denuncias sobre personas que present\u00e1ndose falsamente en nombre de EDEN\u00a0pretenden ingresar a los domicilios de los usuarios argumentando la &#8230; <a title=\"Comunicaci\u00f3n de EDEN ante falsos inspectores\" class=\"read-more\" href=\"https:\/\/www.hoymercedes.com.ar\/principal\/2016\/09\/19\/comunicacion-de-eden-ante-falsos-inspectores\/\" aria-label=\"Leer m\u00e1s sobre Comunicaci\u00f3n de EDEN ante falsos inspectores\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[11],"tags":[10012,10013],"class_list":["post-54844","post","type-post","status-publish","format-standard","hentry","category-ciudad","tag-eden-comunicacion","tag-precaucion","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","wps_subtitle":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/54844","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/comments?post=54844"}],"version-history":[{"count":0,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/54844\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media?parent=54844"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/categories?post=54844"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/tags?post=54844"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}