{"id":55595,"date":"2016-10-07T10:20:03","date_gmt":"2016-10-07T13:20:03","guid":{"rendered":"http:\/\/www.hoymercedes.com.ar\/principal\/?p=55595"},"modified":"2016-10-06T10:21:18","modified_gmt":"2016-10-06T13:21:18","slug":"abogados-invitan-a-disertacion-sobre-violencia-en-redes-sociales","status":"publish","type":"post","link":"https:\/\/www.hoymercedes.com.ar\/principal\/2016\/10\/07\/abogados-invitan-a-disertacion-sobre-violencia-en-redes-sociales\/","title":{"rendered":"Abogados invitan a disertaci\u00f3n sobre violencia en redes sociales"},"content":{"rendered":"<p><em><strong>\u201cLa violencia y la infancia. La violencia en las redes sociales\u201d es el t\u00edtulo de la exposici\u00f3n que har\u00e1 la Dra. Mar\u00eda Jos\u00e9 Lezcano el pr\u00f3ximo 13 de octubre, 18:30 horas, en el Colegio de Abogados. La disertaci\u00f3n es abierta a la comunidad.<\/strong><\/em><\/p>\n<p>A trav\u00e9s de un breve encuentro con los medios, el Colegio de Abogados del Departamento Judicial Mercedes anunci\u00f3 diferentes eventos que realizar\u00e1 en los pr\u00f3ximos d\u00edas y semanas. Actividades que se enmarcan en los festejos del centenario de la instituci\u00f3n y que contin\u00faan con otras actividades que vienen realizando en los \u00faltimos meses.<\/p>\n<p>Para dar a conocer los eventos, la Dra. Patricia Leva habl\u00f3 con los medios y cont\u00f3 las actividades que el Colegio de Abogados realiza para toda la comunidad. \u201cEl a\u00f1o pasado comenzamos con ciclos de conferencias abiertas a la comunidad tratando el tema educativo. Primero hicimos un an\u00e1lisis global, y analizamos las distintas etapas de la educaci\u00f3n\u201d, destac\u00f3 la abogada.<\/p>\n<p>En este 2016, con los festejos y actividades del centenario, el ciclo de charlas continu\u00f3 con temas m\u00e1s concretos, las patolog\u00edas dentro del \u00e1mbito escolar. Es as\u00ed que el mes pasado, se arm\u00f3 una disertaci\u00f3n sobre el bullying con un taller a cargo del Lic. Usandivaras. Para continuar con la tem\u00e1tica, el d\u00eda 13 de octubre, habr\u00e1 una nueva disertaci\u00f3n. En esta oportunidad, el tema ser\u00e1 \u201cLa violencia y la infancia. La violencia en las redes sociales\u201d, a cargo de la Dra. Mar\u00eda Jos\u00e9 Lezcano.<\/p>\n<p>\u201cLa disertaci\u00f3n de la pr\u00f3xima semana ser\u00e1 el tratamiento del bullying a trav\u00e9s de las pantallas, como dice la doctora. A trav\u00e9s de las redes sociales, tambi\u00e9n. La Dra. Lezcano es una excelente persona que tiene un gran curriculum, egresada de la Universidad de Salamanca, y es Doctora del Servicio de Ciencia y Tecnolog\u00eda de la UNLP, adem\u00e1s de ser docente de posgrado en Salud Mental\u201d, resalt\u00f3 la Dra. Leva.<\/p>\n<p>\u201cEste taller es una propuesta con invitaci\u00f3n especial a la comunidad educativa porque son ellos los que m\u00e1s cercanos est\u00e1n a las problem\u00e1ticas de los adolescentes. Aunque es abierto a todo p\u00fablico, a los padres y madres, y a la comunidad en su totalidad. Este es un tema que est\u00e1 en el orden del d\u00eda dentro de las problem\u00e1ticas sociales, atravesadas por la educaci\u00f3n\u201d, agreg\u00f3.<\/p>\n<p>A partir de las 18:30 del pr\u00f3ximo jueves 13 de octubre, la Dra. Lezcano disertar\u00e1 en el Sal\u00f3n de Actos del Colegio de Abogados con entrada libre y gratuita. La instituci\u00f3n invita abiertamente, aunque propone que los interesados se inscriban previamente para realizar los certificados correspondientes a los asistentes. Es as\u00ed que proponen que se comuniquen a la secretar\u00eda del Colegio en el 2\u00ba piso del edificio de 24 y 29.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cLa violencia y la infancia. La violencia en las redes sociales\u201d es el t\u00edtulo de la exposici\u00f3n que har\u00e1 la &#8230; <a title=\"Abogados invitan a disertaci\u00f3n sobre violencia en redes sociales\" class=\"read-more\" href=\"https:\/\/www.hoymercedes.com.ar\/principal\/2016\/10\/07\/abogados-invitan-a-disertacion-sobre-violencia-en-redes-sociales\/\" aria-label=\"Leer m\u00e1s sobre Abogados invitan a disertaci\u00f3n sobre violencia en redes sociales\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[11],"tags":[9616,1734,928],"class_list":["post-55595","post","type-post","status-publish","format-standard","hentry","category-ciudad","tag-charlas","tag-ciudad-2","tag-colegio-de-abogados","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"jetpack_publicize_connections":[],"wps_subtitle":"","jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/55595","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/comments?post=55595"}],"version-history":[{"count":0,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/55595\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media?parent=55595"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/categories?post=55595"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/tags?post=55595"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}