{"id":56002,"date":"2016-10-16T20:23:21","date_gmt":"2016-10-16T23:23:21","guid":{"rendered":"http:\/\/www.hoymercedes.com.ar\/principal\/?p=56002"},"modified":"2016-10-16T20:23:21","modified_gmt":"2016-10-16T23:23:21","slug":"marcela-brown-muestra-ellas-cerraron-las-piernas","status":"publish","type":"post","link":"https:\/\/www.hoymercedes.com.ar\/principal\/2016\/10\/16\/marcela-brown-muestra-ellas-cerraron-las-piernas\/","title":{"rendered":"Marcela Brown muestra \u00abEllas cerraron las piernas\u00bb"},"content":{"rendered":"<p>En la noche del viernes, Marcela Brown present\u00f3 en el Museo de Arte Municipalidad de Mercedes la obra \u00abEllas cerraron las piernas\u00bb. La obra de arte textil que gan\u00f3 el 3\u00b0 premio en el Sal\u00f3n Nacional de Artes Visuales expuesto hasta mediados de septiembre en el Palais de Glace. La exposici\u00f3n local, tiene como particularidad la posibilidad que personas ciegas disfruten de la obra ya que tiene un texto escrito en braille y la oportunidad de sentir las texturas de la pieza.<\/p>\n<p>en la presentaci\u00f3n de la obra ganadora, Marcela dio detalles de c\u00f3mo surgi\u00f3 la obra y la historia real detr\u00e1s de \u00abEllas Cerraron las Piernas\u00bb.\u00a0La obra es una instalaci\u00f3n realizada en tela, goma espuma, guata,silla de madera de \u00e9poca y texto de 100 x 90 x 120 cm. La tem\u00e1tica refiere al genocidio obrero en la d\u00e9cada del 20 en la Patagonia.<\/p>\n<p>En la misma se relata el suceso en San Juli\u00e1n, Santa Cruz del 17 de febrero de 1922, cuando soldados pertenecientes a la tropa de Varela pretenden festejar en el prost\u00edbulo \u201cLa Catalana\u201d el aniquilamiento de los huelguistas de la Patagonia. Las cinco mujeres que trabajan en el lugar se rebelan y se niegan a conceder sus cuerpos a los fusiladores.<\/p>\n<p>Lo interesante de esta presentaci\u00f3n es que la artista ha decidido que sea \u00e9sta una obra inclusiva , haci\u00e9ndola extensiva a personas ciegas. La misma por sus caracter\u00edsticas podr\u00e1 ser recorrida con el tacto y los textos estar\u00e1n adem\u00e1s escritos en braille.<\/p>\n<p>Asimismo, en la presentaci\u00f3n oficial de la obra ganadora, Marcela Brown recibi\u00f3 de manos de los\u00a0concejales la distinci\u00f3n de declaraci\u00f3n de inter\u00e9s legislativo de la pieza art\u00edstica. Es as\u00ed que Mat\u00edas Dematei, Celeste Burone, Mariana San Mart\u00edn y Santiago Altube entregaron el certificado en nombre de todo el cuerpo legislativo. Momento emotivo que cont\u00f3 con la Directora de Cultura Luc\u00eda Capaccio y la directora del MAMM Stella Gonzalez.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"55983\" data-permalink=\"https:\/\/www.hoymercedes.com.ar\/principal\/2016\/10\/16\/marcela-brown-muestra-ellas-cerraron-las-piernas\/16-marce-brown-1\/#main\" data-orig-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2016\/10\/16-marce-brown-1.jpg\" data-orig-size=\"630,420\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;3.5&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;NIKON D3100&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1476475371&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;18&quot;,&quot;iso&quot;:&quot;3200&quot;,&quot;shutter_speed&quot;:&quot;0.02&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"16-marce-brown-1\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2016\/10\/16-marce-brown-1.jpg\" class=\"aligncenter size-medium wp-image-55983\" src=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2016\/10\/16-marce-brown-1-630x420.jpg\" alt=\"16-marce-brown-1\" width=\"630\" height=\"420\" srcset=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2016\/10\/16-marce-brown-1.jpg 630w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2016\/10\/16-marce-brown-1-150x100.jpg 150w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2016\/10\/16-marce-brown-1-300x200.jpg 300w\" sizes=\"auto, (max-width: 630px) 100vw, 630px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"55972\" data-permalink=\"https:\/\/www.hoymercedes.com.ar\/principal\/2016\/10\/16\/marcela-brown-muestra-ellas-cerraron-las-piernas\/16-marce-brown-2\/#main\" data-orig-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2016\/10\/16-marce-brown-2.jpg\" data-orig-size=\"630,420\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;3.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;NIKON D3100&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1476476382&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;24&quot;,&quot;iso&quot;:&quot;2500&quot;,&quot;shutter_speed&quot;:&quot;0.016666666666667&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"16-marce-brown-2\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2016\/10\/16-marce-brown-2.jpg\" class=\"aligncenter size-medium wp-image-55972\" src=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2016\/10\/16-marce-brown-2-630x420.jpg\" alt=\"16-marce-brown-2\" width=\"630\" height=\"420\" srcset=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2016\/10\/16-marce-brown-2.jpg 630w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2016\/10\/16-marce-brown-2-150x100.jpg 150w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2016\/10\/16-marce-brown-2-300x200.jpg 300w\" sizes=\"auto, (max-width: 630px) 100vw, 630px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"55971\" data-permalink=\"https:\/\/www.hoymercedes.com.ar\/principal\/2016\/10\/16\/marcela-brown-muestra-ellas-cerraron-las-piernas\/16-marce-brown-3\/#main\" data-orig-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2016\/10\/16-marce-brown-3.jpg\" data-orig-size=\"630,420\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;3.5&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;NIKON D3100&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1476475396&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;19&quot;,&quot;iso&quot;:&quot;2200&quot;,&quot;shutter_speed&quot;:&quot;0.016666666666667&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"16-marce-brown-3\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2016\/10\/16-marce-brown-3.jpg\" class=\"aligncenter size-medium wp-image-55971\" src=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2016\/10\/16-marce-brown-3-630x420.jpg\" alt=\"16-marce-brown-3\" width=\"630\" height=\"420\" srcset=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2016\/10\/16-marce-brown-3.jpg 630w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2016\/10\/16-marce-brown-3-150x100.jpg 150w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2016\/10\/16-marce-brown-3-300x200.jpg 300w\" sizes=\"auto, (max-width: 630px) 100vw, 630px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En la noche del viernes, Marcela Brown present\u00f3 en el Museo de Arte Municipalidad de Mercedes la obra \u00abEllas cerraron &#8230; <a title=\"Marcela Brown muestra \u00abEllas cerraron las piernas\u00bb\" class=\"read-more\" href=\"https:\/\/www.hoymercedes.com.ar\/principal\/2016\/10\/16\/marcela-brown-muestra-ellas-cerraron-las-piernas\/\" aria-label=\"Leer m\u00e1s sobre Marcela Brown muestra \u00abEllas cerraron las piernas\u00bb\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":55983,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[104],"tags":[7805,4937],"class_list":["post-56002","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura","tag-cultura","tag-marcela-brown","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2016\/10\/16-marce-brown-1.jpg","wps_subtitle":"Expuesta en el MAMM","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/56002","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/comments?post=56002"}],"version-history":[{"count":0,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/56002\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media\/55983"}],"wp:attachment":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media?parent=56002"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/categories?post=56002"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/tags?post=56002"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}