{"id":57157,"date":"2016-11-17T16:09:29","date_gmt":"2016-11-17T19:09:29","guid":{"rendered":"http:\/\/www.hoymercedes.com.ar\/principal\/?p=57157"},"modified":"2016-11-17T14:07:26","modified_gmt":"2016-11-17T17:07:26","slug":"continuan-los-cursos-para-adultos-mayores-para-tener-licencia-de-conducir","status":"publish","type":"post","link":"https:\/\/www.hoymercedes.com.ar\/principal\/2016\/11\/17\/continuan-los-cursos-para-adultos-mayores-para-tener-licencia-de-conducir\/","title":{"rendered":"Contin\u00faan los cursos para adultos mayores para tener licencia de conducir"},"content":{"rendered":"<p>Por Prensa Municipal &#8211; Un nuevo encuentro descentralizado para obtener licencias de conducir para adultos mayores se llev\u00f3 a cabo en el centro de jubilados de calle 50 y 21 con la organizaci\u00f3n de la Secretar\u00eda de Control Urbano. Nuevamente se efectu\u00f3 con participaci\u00f3n de agentes de tr\u00e1nsito y la coordinadora del \u00e1rea Nancy Okos.<\/p>\n<p>La reuni\u00f3n es parte de las actividades que viene planificando Control Urbano y con el objetivo de que nuestros adultos mayores puedan sacar su licencia sin pasar por los tr\u00e1mites m\u00e1s modernos que incluyan, por ejemplo, una computadora, siendo un elemento tecnol\u00f3gico que no est\u00e1n habituados a utilizar.<\/p>\n<p>\u201cEl municipio contin\u00faa acerc\u00e1ndose a los barrios, a los vecinos, a los Centros de Jubilados, Sociedades de Fomento, Clubes, para directamente hablar con ellos y en este caso con los adultos mayores donde a la hora de brindarles la posibilidad de sacar la licencia de conducir ten\u00edamos un problema muy grande porque para muchos es muy estresante ya que sin licencia no pueden manejar y desde lo psicol\u00f3gico a cierta edad es muy fuerte, una p\u00e9rdida muy grande y el problema para ellos es la tecnolog\u00eda\u201d coment\u00f3 destacando que \u201csiendo una generaci\u00f3n que no se cri\u00f3 al calor de las nuevas expresiones tecnol\u00f3gicas es l\u00f3gico que no se sientan c\u00f3modos\u201d<\/p>\n<p>A los adultos mayores se les genera de \u00e9sta manera un proceso de ense\u00f1anza aprendizaje y renovaci\u00f3n de su carnet de conducir en funci\u00f3n de sus realidades. Descentralizando, ahorrando burocracias y apostando a mejores y mayores servicios.\u00a0En esta ocasi\u00f3n fue en el Centro de Jubilados de calle 50 y 21.<\/p>\n<p>&nbsp;<\/p>\n<p>Fuente: Prensa Municipal<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Prensa Municipal &#8211; Un nuevo encuentro descentralizado para obtener licencias de conducir para adultos mayores se llev\u00f3 a cabo &#8230; <a title=\"Contin\u00faan los cursos para adultos mayores para tener licencia de conducir\" class=\"read-more\" href=\"https:\/\/www.hoymercedes.com.ar\/principal\/2016\/11\/17\/continuan-los-cursos-para-adultos-mayores-para-tener-licencia-de-conducir\/\" aria-label=\"Leer m\u00e1s sobre Contin\u00faan los cursos para adultos mayores para tener licencia de conducir\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":57158,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[30],"tags":[1616,5907],"class_list":["post-57157","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipio","tag-control-urbano","tag-transito","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"jetpack_publicize_connections":[],"wps_subtitle":"Repercusi\u00f3n entre los vecinos","jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2016\/11\/17-transito-adultos.jpg","_links":{"self":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/57157","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/comments?post=57157"}],"version-history":[{"count":0,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/57157\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media\/57158"}],"wp:attachment":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media?parent=57157"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/categories?post=57157"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/tags?post=57157"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}