{"id":60194,"date":"2017-03-01T09:24:07","date_gmt":"2017-03-01T12:24:07","guid":{"rendered":"http:\/\/www.hoymercedes.com.ar\/principal\/?p=60194"},"modified":"2017-03-01T09:24:07","modified_gmt":"2017-03-01T12:24:07","slug":"castraciones-en-barrio-guemes","status":"publish","type":"post","link":"https:\/\/www.hoymercedes.com.ar\/principal\/2017\/03\/01\/castraciones-en-barrio-guemes\/","title":{"rendered":"Castraciones en Barrio G\u00fcemes"},"content":{"rendered":"<p>La Sociedad de Fomento del Barrio G\u00fcemes en conjunto con el \u00e1rea Veterinaria del Municipio, informaron que los d\u00edas 9 y 10 de marzo se llevar\u00e1n adelante castraciones para perros\/as y gatos\/as. Entre las 8 y las 13 horas, las operaciones se realizar\u00e1n en la sede de calle 45 entre 36 y 38. Los animales a castrar deber\u00e1n tener un ayudo de 12 horas, bozal en el caso de ser animales mordedores y llevar una manta para despu\u00e9s de la cirug\u00eda.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Sociedad de Fomento del Barrio G\u00fcemes en conjunto con el \u00e1rea Veterinaria del Municipio, informaron que los d\u00edas 9 &#8230; <a title=\"Castraciones en Barrio G\u00fcemes\" class=\"read-more\" href=\"https:\/\/www.hoymercedes.com.ar\/principal\/2017\/03\/01\/castraciones-en-barrio-guemes\/\" aria-label=\"Leer m\u00e1s sobre Castraciones en Barrio G\u00fcemes\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[11],"tags":[9830,1734,244,9831],"class_list":["post-60194","post","type-post","status-publish","format-standard","hentry","category-ciudad","tag-castracion","tag-ciudad-2","tag-municipio-2","tag-veterinaria","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"jetpack_publicize_connections":[],"wps_subtitle":"","jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/60194","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/comments?post=60194"}],"version-history":[{"count":0,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/60194\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media?parent=60194"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/categories?post=60194"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/tags?post=60194"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}