{"id":61219,"date":"2017-03-30T19:00:44","date_gmt":"2017-03-30T22:00:44","guid":{"rendered":"http:\/\/www.hoymercedes.com.ar\/principal\/?p=61219"},"modified":"2017-03-30T17:07:03","modified_gmt":"2017-03-30T20:07:03","slug":"cine-la-bella-y-la-bestia-suman-vida-iteligente","status":"publish","type":"post","link":"https:\/\/www.hoymercedes.com.ar\/principal\/2017\/03\/30\/cine-la-bella-y-la-bestia-suman-vida-iteligente\/","title":{"rendered":"Cine: La Bella y la Bestia suman Vida Iteligente"},"content":{"rendered":"<p>El \u00e9xito absoluto en las funciones de La Bella y la Bestia en Mercedes, mereci\u00f3 que el Cine Mercedes contin\u00fae\u00a0una semana m\u00e1s la pel\u00edcula de Disney con actores humanos y personajes animados. Es as\u00ed que este film podr\u00e1 verse desde el viernes 31 de marzo y hasta el martes 4 de abril en las funciones de la tarde. Las funciones en castellano son a la hora 19 y el s\u00e1bado y domingo se suma la funci\u00f3n a la hora 16.<\/p>\n<p>A la cartelera de este semana se le suma otra pel\u00edcula. Los amantes del suspenso y la ciencia ficci\u00f3n podr\u00e1n ver la pel\u00edcula de\u00a0Ryan Reynolds, Jake Gyllenhaal y Rebecca Ferguson, bajo el t\u00edtulo \u00abLife &#8211; Vida Inteligente\u00bb. Las funciones son a la hora 22 y el s\u00e1bado a la medianoche.<\/p>\n<p>La Bella y la Bestia entonces podr\u00e1 verse de del viernes 31 de marzo al martes 4 de abril. El viernes, lunes y martes la funci\u00f3n es a la 19, en castellano, y el s\u00e1bado y domingo a las 16 y 19\u00a0en\u00a0castellano. Sinopsis:\u00a0Cuenta el fant\u00e1stico viaje de Bella, una joven brillante, hermosa e independiente, que es tomada prisionera por una bestia en su castillo. A pesar de sus temores, ella entabla una amistad con el personal del castillo encantado y logra ver m\u00e1s all\u00e1 del abominable aspecto de la Bestia, donde se esconde el coraz\u00f3n y el alma de un verdadero pr\u00edncipe.<\/p>\n<p><span class=\"embed-youtube\" style=\"text-align:center; display: block;\"><iframe loading=\"lazy\" class=\"youtube-player\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/CkvpL8Fx7WA?version=3&#038;rel=1&#038;showsearch=0&#038;showinfo=1&#038;iv_load_policy=1&#038;fs=1&#038;hl=es-ES&#038;autohide=2&#038;wmode=transparent\" allowfullscreen=\"true\" style=\"border:0;\" sandbox=\"allow-scripts allow-same-origin allow-popups allow-presentation allow-popups-to-escape-sandbox\"><\/iframe><\/span><\/p>\n<p>Por su parte, \u00abLife &#8211; Vida Inteligente\u00bb\u00a0podr\u00e1 verse del viernes 31 de marzo al martes 4 de abril en la funci\u00f3n de la hora 22,\u00a0subtitulada, y el s<span class=\"text_exposed_show\">\u00e1bado trasnoche (0:00 horas \u00a0&#8211; subtitulada). Sinopsis:\u00a0Life narra la historia de los seis miembros de la tripulaci\u00f3n de la Estaci\u00f3n Espacial Internacional que est\u00e1n a punto de lograr uno de los descubrimientos m\u00e1s importantes en la historia humana: la primera evidencia de vida extraterrestre en Marte. A medida que el equipo comienza a investigar y sus m\u00e9todos tienen consecuencias inesperadas, la forma viviente demostrar\u00e1 ser m\u00e1s inteligente de lo que cualquiera esperaba.<\/span><\/p>\n<p><span class=\"embed-youtube\" style=\"text-align:center; display: block;\"><iframe loading=\"lazy\" class=\"youtube-player\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/49ggboAUN-w?version=3&#038;rel=1&#038;showsearch=0&#038;showinfo=1&#038;iv_load_policy=1&#038;fs=1&#038;hl=es-ES&#038;autohide=2&#038;wmode=transparent\" allowfullscreen=\"true\" style=\"border:0;\" sandbox=\"allow-scripts allow-same-origin allow-popups allow-presentation allow-popups-to-escape-sandbox\"><\/iframe><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El \u00e9xito absoluto en las funciones de La Bella y la Bestia en Mercedes, mereci\u00f3 que el Cine Mercedes contin\u00fae\u00a0una &#8230; <a title=\"Cine: La Bella y la Bestia suman Vida Iteligente\" class=\"read-more\" href=\"https:\/\/www.hoymercedes.com.ar\/principal\/2017\/03\/30\/cine-la-bella-y-la-bestia-suman-vida-iteligente\/\" aria-label=\"Leer m\u00e1s sobre Cine: La Bella y la Bestia suman Vida Iteligente\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":60982,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[104],"tags":[8770,984,7805,8642],"class_list":["post-61219","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura","tag-cartelera","tag-cine-mercedes","tag-cultura","tag-programacion","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2017\/03\/23-cine-bella-bestia.jpg","wps_subtitle":"Cartelera","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/61219","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/comments?post=61219"}],"version-history":[{"count":0,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/61219\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media\/60982"}],"wp:attachment":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media?parent=61219"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/categories?post=61219"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/tags?post=61219"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}