{"id":64371,"date":"2017-06-29T21:40:47","date_gmt":"2017-06-30T00:40:47","guid":{"rendered":"http:\/\/www.hoymercedes.com.ar\/principal\/?p=64371"},"modified":"2017-06-29T21:51:52","modified_gmt":"2017-06-30T00:51:52","slug":"ustarroz-confirmo-que-se-iniciaron-estudios-de-suelo-en-avenida-2-previos-a-su-repavimentacion","status":"publish","type":"post","link":"https:\/\/www.hoymercedes.com.ar\/principal\/2017\/06\/29\/ustarroz-confirmo-que-se-iniciaron-estudios-de-suelo-en-avenida-2-previos-a-su-repavimentacion\/","title":{"rendered":"Ustarroz confirm\u00f3 que se iniciaron estudios de suelo en Avenida 2 previos a su repavimentaci\u00f3n"},"content":{"rendered":"<p><span class=\"embed-youtube\" style=\"text-align:center; display: block;\"><iframe loading=\"lazy\" class=\"youtube-player\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/l1KYPtbkYQA?version=3&#038;rel=1&#038;showsearch=0&#038;showinfo=1&#038;iv_load_policy=1&#038;fs=1&#038;hl=es-ES&#038;autohide=2&#038;wmode=transparent\" allowfullscreen=\"true\" style=\"border:0;\" sandbox=\"allow-scripts allow-same-origin allow-popups allow-presentation allow-popups-to-escape-sandbox\"><\/iframe><\/span><\/p>\n<p>El intendente confirm\u00f3 que se iniciaron los estudios correspondientes de suelo sobre avenida 2 en lo que es una muy buena noticia para todos los mercedinos. La importante cantidad de gestiones efectuadas por la Comuna encontr\u00f3 hoy un valioso momento cuando se arranc\u00f3 con el llamado \u201cCalicata\u201d que es el estudio previo a toda repavimentaci\u00f3n.<\/p>\n<p>Juan Ignacio Ustarroz expres\u00f3 que \u201cestamos realmente muy contentos porque empez\u00f3 el estudio de calicata para poder avanzar luego en un proyecto de repavimentaci\u00f3n de toda la avenida 2 desde la rotonda hasta calle 29\u201d coment\u00f3 destacando que \u201cmucho hemos trabajado por esto con la gente de Vialidad Nacional, con Ezequiel Bissio que colabora y colabor\u00f3 much\u00edsimo, tambi\u00e9n Carla Picolomini, la Uni\u00f3n de Usuarios Viales. Esta es la filosof\u00eda, encontrar una soluci\u00f3n a uno de los problemas estructurales que tiene Mercedes y en este caso que tiene que ver con su principal acceso que es el que est\u00e1 en peores condiciones y hoy vemos con muchas expectativas y esperanzas que se avanza y es lo importante\u201d, remarc\u00f3 el intendente Comunal.<\/p>\n<figure id=\"attachment_64372\" aria-describedby=\"caption-attachment-64372\" style=\"width: 620px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"64372\" data-permalink=\"https:\/\/www.hoymercedes.com.ar\/principal\/2017\/06\/29\/ustarroz-confirmo-que-se-iniciaron-estudios-de-suelo-en-avenida-2-previos-a-su-repavimentacion\/avenida-4\/#main\" data-orig-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2017\/06\/Avenida-4.jpg\" data-orig-size=\"884,589\" data-comments-opened=\"0\" data-image-title=\"Avenida-4\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Estudio de Calicata en Avenida N2&lt;\/p&gt;\n\" data-large-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2017\/06\/Avenida-4.jpg\" class=\"size-medium wp-image-64372\" src=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2017\/06\/Avenida-4-630x420.jpg\" alt=\"\" width=\"630\" height=\"420\" srcset=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2017\/06\/Avenida-4-630x420.jpg 630w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2017\/06\/Avenida-4-150x100.jpg 150w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2017\/06\/Avenida-4-300x200.jpg 300w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2017\/06\/Avenida-4.jpg 884w\" sizes=\"auto, (max-width: 630px) 100vw, 630px\" \/><figcaption id=\"caption-attachment-64372\" class=\"wp-caption-text\">Estudio de Calicata en Avenida N2<\/figcaption><\/figure>\n<p>El estudio de Calicata es una de las t\u00e9cnicas de exploraci\u00f3n empleadas para facilitar el reconocimiento geot\u00e9cnico de un terreno. Son excavaciones de profundidad peque\u00f1a a media. Permiten la inspecci\u00f3n directa del suelo que se desea estudiar y, por lo tanto, es el m\u00e9todo de exploraci\u00f3n que normalmente entrega la informaci\u00f3n m\u00e1s confiable y completa.<\/p>\n<p>\u201cHace poco Ezequiel me dec\u00eda que estaba incorporado en el presupuesto dentro del tramo de Ruta N\u00b05 as\u00ed que gratamente estamos hoy con estos trabajadores haciendo estos estudios y vemos que se avanza ya esperando en breve el inicio de esta obra que va a ser tan importante para Mercedes\u201d, coment\u00f3 Juan Ignacio Ustarroz.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El intendente confirm\u00f3 que se iniciaron los estudios correspondientes de suelo sobre avenida 2 en lo que es una muy &#8230; <a title=\"Ustarroz confirm\u00f3 que se iniciaron estudios de suelo en Avenida 2 previos a su repavimentaci\u00f3n\" class=\"read-more\" href=\"https:\/\/www.hoymercedes.com.ar\/principal\/2017\/06\/29\/ustarroz-confirmo-que-se-iniciaron-estudios-de-suelo-en-avenida-2-previos-a-su-repavimentacion\/\" aria-label=\"Leer m\u00e1s sobre Ustarroz confirm\u00f3 que se iniciaron estudios de suelo en Avenida 2 previos a su repavimentaci\u00f3n\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":64372,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[30],"tags":[11435],"class_list":["post-64371","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipio","tag-repavimentacion-avenida-2","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2017\/06\/Avenida-4.jpg","wps_subtitle":"Obra necesaria","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/64371","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/comments?post=64371"}],"version-history":[{"count":0,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/64371\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media\/64372"}],"wp:attachment":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media?parent=64371"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/categories?post=64371"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/tags?post=64371"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}