{"id":64766,"date":"2017-07-10T18:30:09","date_gmt":"2017-07-10T21:30:09","guid":{"rendered":"http:\/\/www.hoymercedes.com.ar\/principal\/?p=64766"},"modified":"2017-07-10T17:40:05","modified_gmt":"2017-07-10T20:40:05","slug":"teatro-en-la-escuela-y-a-esa-quien-la-conoce","status":"publish","type":"post","link":"https:\/\/www.hoymercedes.com.ar\/principal\/2017\/07\/10\/teatro-en-la-escuela-y-a-esa-quien-la-conoce\/","title":{"rendered":"Teatro en la Escuela: \u201c\u00bfY a esa, qui\u00e9n la conoce?\u00bb.\u00a0"},"content":{"rendered":"<p>Este mi\u00e9rcoles 12 de julio, a la hora 15, el sal\u00f3n de actos de la Escuela Primaria N\u00b0 1 (calle 24 y 15) \u00a0se volver\u00e1 una sala de teatro abierta a la comunidad en donde se estrenar\u00e1 una obra de creaci\u00f3n colectiva de los alumnos del Instituto Superior de Formaci\u00f3n Docente y T\u00e9cnica N\u00b0 7 (entidad educativa que funciona en el mismo edificio), titulada\u00a0\u201c\u00bfY a esa, qui\u00e9n la conoce?\u00bb.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"64767\" data-permalink=\"https:\/\/www.hoymercedes.com.ar\/principal\/2017\/07\/10\/teatro-en-la-escuela-y-a-esa-quien-la-conoce\/10-obra-isfdyt7\/#main\" data-orig-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2017\/07\/10-obra-ISFDyT7.jpg\" data-orig-size=\"630,420\" data-comments-opened=\"0\" data-image-title=\"10 obra ISFDyT7\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2017\/07\/10-obra-ISFDyT7.jpg\" class=\"aligncenter size-medium wp-image-64767\" src=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2017\/07\/10-obra-ISFDyT7-630x420.jpg\" alt=\"\" width=\"630\" height=\"420\" srcset=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2017\/07\/10-obra-ISFDyT7.jpg 630w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2017\/07\/10-obra-ISFDyT7-150x100.jpg 150w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2017\/07\/10-obra-ISFDyT7-300x200.jpg 300w\" sizes=\"auto, (max-width: 630px) 100vw, 630px\" \/><\/p>\n<p>La propuesta teatral, con entrada libre y gratuita, est\u00e1 realizada dirigida por la profesora Carolina Pisoni y Paola Banegas. El elenco lo integran Cintia Brindo Defelippe, Lorena Gutierrez, Maira Ojeda, Micaela Recalde, Paola Banegas, Manuela Vila y Catalina D\u00edaz Pisoni. La puesta en escena se complementa con la musicalizaci\u00f3n de Paola Palacios con la colaboraci\u00f3n de Chiara Rossi. En tanto, la fotograf\u00eda est\u00e1 a cargo de Kajtek Pietrzykowski y la edici\u00f3n de Jennifer Ojeda.<\/p>\n<p>Sinopsis de \u201c\u00bfY a esa, qui\u00e9n la conoce?\u00bb:\u00a0Juan, un adolescente com\u00fan y silvestre, tiene un problema y muchas dificultades para resolverlo: las tareas escolares de Pr\u00e1cticas del Lenguaje. Una nube de ensue\u00f1os, sin embargo, lo llevar\u00e1 por caminos extra\u00f1os donde conocer\u00e1 a personajes raros -pero m\u00e1s cercanos de lo que \u00e9l cre\u00eda- que le cambiar\u00e1n la vida para siempre, en el camino hacia la madurez. \u201c\u00bfY a esa, qui\u00e9n la conoce?\u00bb se plantea como un camino inici\u00e1tico en el devenir de un joven millennial del subdesarrollo.<\/p>\n<p>\u201c\u00bfY a esa, qui\u00e9n la conoce?\u00bb es una obra colectiva creada por alumnos del Profesorado para la Ense\u00f1anza Secundaria en Lengua y Literatura del ISFD y T N\u00ba 7 de Mercedes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este mi\u00e9rcoles 12 de julio, a la hora 15, el sal\u00f3n de actos de la Escuela Primaria N\u00b0 1 (calle &#8230; <a title=\"Teatro en la Escuela: \u201c\u00bfY a esa, qui\u00e9n la conoce?\u00bb.\u00a0\" class=\"read-more\" href=\"https:\/\/www.hoymercedes.com.ar\/principal\/2017\/07\/10\/teatro-en-la-escuela-y-a-esa-quien-la-conoce\/\" aria-label=\"Leer m\u00e1s sobre Teatro en la Escuela: \u201c\u00bfY a esa, qui\u00e9n la conoce?\u00bb.\u00a0\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":64767,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[104,23],"tags":[7805,47,11503,11504],"class_list":["post-64766","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura","category-educacion","tag-cultura","tag-educacion-2","tag-isfdyt-n-7","tag-profesorado-de-lengua-y-literatura","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2017\/07\/10-obra-ISFDyT7.jpg","wps_subtitle":"En la Escuela 1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/64766","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/comments?post=64766"}],"version-history":[{"count":0,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/64766\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media\/64767"}],"wp:attachment":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media?parent=64766"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/categories?post=64766"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/tags?post=64766"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}