{"id":65181,"date":"2017-07-22T20:53:36","date_gmt":"2017-07-22T23:53:36","guid":{"rendered":"http:\/\/www.hoymercedes.com.ar\/principal\/?p=65181"},"modified":"2017-07-22T21:02:52","modified_gmt":"2017-07-23T00:02:52","slug":"nuestros-adultos-mayores-son-un-sector-muy-golpeado-destacan-desde-unidad-ciudadana","status":"publish","type":"post","link":"https:\/\/www.hoymercedes.com.ar\/principal\/2017\/07\/22\/nuestros-adultos-mayores-son-un-sector-muy-golpeado-destacan-desde-unidad-ciudadana\/","title":{"rendered":"\u201cNuestros adultos mayores son un sector muy golpeado\u201d destacan desde Unidad Ciudadana"},"content":{"rendered":"<figure id=\"attachment_65182\" aria-describedby=\"caption-attachment-65182\" style=\"width: 620px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"65182\" data-permalink=\"https:\/\/www.hoymercedes.com.ar\/principal\/2017\/07\/22\/nuestros-adultos-mayores-son-un-sector-muy-golpeado-destacan-desde-unidad-ciudadana\/adultosmayores-1\/#main\" data-orig-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2017\/07\/AdultosMayores-1.jpg\" data-orig-size=\"630,419\" data-comments-opened=\"0\" data-image-title=\"AdultosMayores-1\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2017\/07\/AdultosMayores-1.jpg\" class=\"wp-image-65182 size-medium\" src=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2017\/07\/AdultosMayores-1-630x419.jpg\" alt=\"\" width=\"630\" height=\"419\" srcset=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2017\/07\/AdultosMayores-1.jpg 630w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2017\/07\/AdultosMayores-1-150x100.jpg 150w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2017\/07\/AdultosMayores-1-300x200.jpg 300w\" sizes=\"auto, (max-width: 630px) 100vw, 630px\" \/><figcaption id=\"caption-attachment-65182\" class=\"wp-caption-text\">Encuentro en Circulo Italiano<\/figcaption><\/figure>\n<p>M\u00e1s de cien adultos mayores y vecinos fueron parte del encuentro realizado en el \u00e1mbito de la Sociedad Italiana de nuestra ciudad organizado por Unidad Ciudadana. Debate, reflexi\u00f3n, intercambio y tambi\u00e9n una merienda para el encuentro ciudadano.<\/p>\n<p>La reuni\u00f3n tuvo como objetivo el encuentro, el debate y la reflexi\u00f3n con una mirada de nuestros adultos mayores donde con un t\u00e9 de por medio tambi\u00e9n se vivi\u00f3 un momento musical junto a \u00abJulio Moreno y el Tr\u00edo los amigos\u00bb que a todo folklore y m\u00fasica bien Argentina permitieron un bello momento.<\/p>\n<p>En las mesas, entre caf\u00e9, t\u00e9 y confituras se di\u00e1logo y debati\u00f3 la actualidad del pa\u00eds y la ciudad con la participaci\u00f3n de los candidatos de UC.<\/p>\n<p>\u00abNacho\u00bb Cassiani, Victoria Odell, Marcela Brown, Diego Saavedra, Ger\u00f3nimo Ustarroz, Mariana Alfred, N\u00e9lida Garc\u00eda, Silvia Ju\u00e1rez, Alejandra Solul\u00e9, Mariana San Mart\u00edn, Celeste Burone, fueron parte del encuentro junto a funcionarios como Tatiana L\u00f3pez y el presidente del Concejo Deliberante, Mat\u00edas Dematei.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"65183\" data-permalink=\"https:\/\/www.hoymercedes.com.ar\/principal\/2017\/07\/22\/nuestros-adultos-mayores-son-un-sector-muy-golpeado-destacan-desde-unidad-ciudadana\/adultosmayores-4\/#main\" data-orig-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2017\/07\/AdultosMayores-4.jpg\" data-orig-size=\"630,419\" data-comments-opened=\"0\" data-image-title=\"AdultosMayores-4\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2017\/07\/AdultosMayores-4.jpg\" class=\"aligncenter size-medium wp-image-65183\" src=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2017\/07\/AdultosMayores-4-630x419.jpg\" alt=\"\" width=\"630\" height=\"419\" srcset=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2017\/07\/AdultosMayores-4.jpg 630w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2017\/07\/AdultosMayores-4-150x100.jpg 150w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2017\/07\/AdultosMayores-4-300x200.jpg 300w\" sizes=\"auto, (max-width: 630px) 100vw, 630px\" \/><\/p>\n<p>Por su parte, Juan Ignacio Ustarroz remarc\u00f3 el valor inagotable que \u00abtienen estos encuentros donde nos vemos, intercambiamos y construimos juntos, que es la \u00fanica manera de afrontar una realidad compleja, cada d\u00eda m\u00e1s dif\u00edcil\u00bb y sin olvidar que \u201cnuestros adultos mayores son uno de los sectores m\u00e1s golpeados, con menos coberturas m\u00e9dicas, sin medicamentos. El recuerdo de lo que fue el PAMI hace tan poco tiempo atr\u00e1s y lo que es ahora su realidad sin duda muestra un contraste fuerte en la p\u00e9rdida de derechos\u201d.<\/p>\n<p>Quien tambi\u00e9n tuvo palabras de elogio a la reuni\u00f3n fue Ger\u00f3nimo \u00abZaza\u00bb Ustarroz expresando que \u00abellos, nuestros adultos mayores, vecinos y mercedinos, no s\u00f3lo son la voz de la experiencia, sino tambi\u00e9n la reflexi\u00f3n serena y profunda, cuando nos cuentan que el tarifazo es grave, que los alimentos no paran de aumentar, que dudan cada vez que hay que prender la calefacci\u00f3n a gas nos est\u00e1n narrando el dolor de una actualidad dif\u00edcil que nos golpea a todos\u00bb sostuvo.<\/p>\n<p>Amadeo, quien se acerc\u00f3 desde Villa Industrial, sostuvo ante los medios que \u00abno tengo dudas. Esto tiene que cambiar. No alcanza la guita. Nos mintieron y por eso empec\u00e9 a participar de estas reuniones. Duele mucho ver todo lo que est\u00e1 pasando. Yo gasto en un solo remedia 2000 pesos y tomo cinco distintos\u00bb cont\u00f3 visiblemente emocionado y dijo que \u201ctengo tantas cosas que no te las podr\u00eda contar, s\u00f3lo s\u00e9 que cada vez que voy a hacer un tr\u00e1mite no nos dan bola\u201d.<\/p>\n<p>El trabajo en conjunto con la sociedad es un tema clave, remarcaron y afirmaron que no se trata de una expresi\u00f3n pol\u00edtica, sino de defender los derechos de cada de los vecinos.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Fuente: Unidad Ciudadana Mercedes<\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00e1s de cien adultos mayores y vecinos fueron parte del encuentro realizado en el \u00e1mbito de la Sociedad Italiana de &#8230; <a title=\"\u201cNuestros adultos mayores son un sector muy golpeado\u201d destacan desde Unidad Ciudadana\" class=\"read-more\" href=\"https:\/\/www.hoymercedes.com.ar\/principal\/2017\/07\/22\/nuestros-adultos-mayores-son-un-sector-muy-golpeado-destacan-desde-unidad-ciudadana\/\" aria-label=\"Leer m\u00e1s sobre \u201cNuestros adultos mayores son un sector muy golpeado\u201d destacan desde Unidad Ciudadana\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":65183,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[5],"tags":[11572,11544],"class_list":["post-65181","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-adultos-mayores-unidad-ciudadana","tag-unidad-ciudadana-mercedes","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2017\/07\/AdultosMayores-4.jpg","wps_subtitle":"Encuentro ","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/65181","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/comments?post=65181"}],"version-history":[{"count":0,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/65181\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media\/65183"}],"wp:attachment":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media?parent=65181"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/categories?post=65181"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/tags?post=65181"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}