{"id":65940,"date":"2017-08-12T09:26:27","date_gmt":"2017-08-12T12:26:27","guid":{"rendered":"http:\/\/www.hoymercedes.com.ar\/principal\/?p=65940"},"modified":"2017-08-12T11:37:13","modified_gmt":"2017-08-12T14:37:13","slug":"nicolas-dematei-debuta-en-rafaela-por-la-copa-santa-fe","status":"publish","type":"post","link":"https:\/\/www.hoymercedes.com.ar\/principal\/2017\/08\/12\/nicolas-dematei-debuta-en-rafaela-por-la-copa-santa-fe\/","title":{"rendered":"Nicol\u00e1s Dematei debuta en Rafaela por la Copa Santa Fe"},"content":{"rendered":"<p><strong>Diario La Opini\u00f3n.<em> Atl\u00e9tico de Rafaela contin\u00faa sumando rodaje\u00a0en esta preparaci\u00f3n de invierno y, con la cabeza puesta en el juego de semifinal de Copa Santa Fe de este s\u00e1bado, el DT prob\u00f3 un equipo con la inclusi\u00f3n desde el minuto inicial de\u00a0Gonzalo Klusener y\u00a0de\u00a0Nicol\u00e1s Dematei. La otra variante que presentar\u00eda Lucas Bovaglio ser\u00eda la del ingreso del juvenil Lucas Quiroz.\u00a0<\/em><\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"65941\" data-permalink=\"https:\/\/www.hoymercedes.com.ar\/principal\/2017\/08\/12\/nicolas-dematei-debuta-en-rafaela-por-la-copa-santa-fe\/nicolas-dematei-rafaela\/#main\" data-orig-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2017\/08\/Nicolas-Dematei-Rafaela.jpg\" data-orig-size=\"1871,1655\" data-comments-opened=\"0\" data-image-title=\"Nicolas Dematei Rafaela\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2017\/08\/Nicolas-Dematei-Rafaela-1024x906.jpg\" class=\"aligncenter size-medium wp-image-65941\" src=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2017\/08\/Nicolas-Dematei-Rafaela-630x557.jpg\" alt=\"\" width=\"630\" height=\"557\" srcset=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2017\/08\/Nicolas-Dematei-Rafaela-630x557.jpg 630w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2017\/08\/Nicolas-Dematei-Rafaela-150x133.jpg 150w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2017\/08\/Nicolas-Dematei-Rafaela-1024x906.jpg 1024w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2017\/08\/Nicolas-Dematei-Rafaela.jpg 1871w\" sizes=\"auto, (max-width: 630px) 100vw, 630px\" \/><\/p>\n<p>El delantero ya tuvo su debut en la \u2018Crema\u2019, el pasado domingo en Las Parejas, pero ser\u00edan los primeros minutos en cancha del defensor exGuillermo Brown de Puerto Madry.<br \/>\n\u00bfEl probable?:\u00a0Ramiro Macagno; Oscar Carniello, Wilfredo Olivera, Franco Lazzaroni y Dematei;\u00a0Quiroz, Emiliano Romero y Jorge Vel\u00e1zquez; Enzo Copetti, Klusener y Mauro Albertengo.<\/p>\n<p>Sobre la posibilidad de concretar su debut este s\u00e1bado a las 15.30 hs. vs Sportivo Rivadavia de Venado Tuerto en el estadio Monumental y su arribo a la \u2018Crema\u2019, Dematei charl\u00f3 con La Opini\u00f3n:<\/p>\n<p>\u201cNo me lo confirm\u00f3 todav\u00eda pero me recibi\u00f3 muy bien\u201d, apunt\u00f3 Nicol\u00e1s Dematei en relaci\u00f3n a Bovaglio, quien lo incluy\u00f3 en los dos trabajos t\u00e1cticos-futbol\u00edsticos de la semana en el equipo titular. Si bien el lateral zurdo se sum\u00f3 el \u00faltimo martes a los trabajos de la \u2018Crema\u2019, hasta hace un par de semanas estuvo en actividad en el certamen de la B Nacional. \u201cTermin\u00e9 hace poco, en lo f\u00edsico estoy bien as\u00ed que si el t\u00e9cnico lo dispone estoy para jugar, espero que sea de la mejor manera\u201d, se\u00f1al\u00f3.<\/p>\n<p>En relaci\u00f3n a su llegada a Rafaela, Dematei cont\u00f3:\u00a0\u201cCuando me dijeron que estaba la posibilidad ni lo dud\u00e9, me sedujo mucho\u00a0y por suerte se pudo resolver todo r\u00e1pido para poder sumarme a Atl\u00e9tico\u201d. Y en relaci\u00f3n a sus nuevos compa\u00f1eros manifest\u00f3: \u201cLa verdad que estoy contento, el grupo me ha recibido muy bien as\u00ed que con muchas ganas\u201d.<\/p>\n<p>El elenco de barrio Alberdi se va formando. Se van sumando los refuerzos y conformando el plantel con el objetivo de ser uno de los animadores del pr\u00f3ximo campeonato de la Primera B Nacional.<br \/>\n\u201cLa idea es tratar de ser un equipo protagonista pero tenemos que estar tranquilos, ir de a poco va a ser largo y tambi\u00e9n a su vez pasa r\u00e1pido\u00a0pero tenemos que estar tranquilos para hacer una buena pretemporada y llegar de la mejor manera al torneo que se viene\u201d, cont\u00f3 Dematei, de 29 a\u00f1os de edad.<\/p>\n<p>En relaci\u00f3n a sus primeras charlas con el cuerpo t\u00e9cnico y \u2018Nano\u2019 Clementz, conocedor del puesto que ocupar\u00e1 Nicol\u00e1s, el exGuillermo Brown confes\u00f3: \u201cEstuvimos hablando un poco, uno trata de seguir aprendiendo, de seguir creciendo y es por eso que siempre uno toma los concejos y todo lo que sea para sumar siempre es muy bienvenido\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Diario La Opini\u00f3n. Atl\u00e9tico de Rafaela contin\u00faa sumando rodaje\u00a0en esta preparaci\u00f3n de invierno y, con la cabeza puesta en el &#8230; <a title=\"Nicol\u00e1s Dematei debuta en Rafaela por la Copa Santa Fe\" class=\"read-more\" href=\"https:\/\/www.hoymercedes.com.ar\/principal\/2017\/08\/12\/nicolas-dematei-debuta-en-rafaela-por-la-copa-santa-fe\/\" aria-label=\"Leer m\u00e1s sobre Nicol\u00e1s Dematei debuta en Rafaela por la Copa Santa Fe\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":65941,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[21],"tags":[11706,11704,204,3528,11705],"class_list":["post-65940","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes","tag-copa-santa-fe","tag-debut","tag-deportes-2","tag-nicolas-dematei","tag-rafaela","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"jetpack_publicize_connections":[],"wps_subtitle":"La Legi\u00f3n","jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2017\/08\/Nicolas-Dematei-Rafaela.jpg","_links":{"self":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/65940","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/comments?post=65940"}],"version-history":[{"count":0,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/65940\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media\/65941"}],"wp:attachment":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media?parent=65940"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/categories?post=65940"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/tags?post=65940"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}