{"id":69668,"date":"2017-11-14T11:29:36","date_gmt":"2017-11-14T14:29:36","guid":{"rendered":"http:\/\/www.hoymercedes.com.ar\/principal\/?p=69668"},"modified":"2017-11-13T21:56:25","modified_gmt":"2017-11-14T00:56:25","slug":"quilmes-se-quedo-con-el-primero-de-los-clasicos-por-el-quinto-puesto","status":"publish","type":"post","link":"https:\/\/www.hoymercedes.com.ar\/principal\/2017\/11\/14\/quilmes-se-quedo-con-el-primero-de-los-clasicos-por-el-quinto-puesto\/","title":{"rendered":"Quilmes se qued\u00f3 con el primero de los cl\u00e1sicos por el quinto puesto"},"content":{"rendered":"<p><em><strong>Quilmes gan\u00f3 el cl\u00e1sico ante Estudiantes poniendo la serie 1 a 0 en la Copa de Plata. En un partido parejo y con un mejor juego de Estudiantes en el PT (termin\u00f3 34-31 arriba), Quilmes lo dio vuelta en juego y resultado en el ST para terminar ganando sin sobresaltos.<\/strong><\/em><\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_69671\" aria-describedby=\"caption-attachment-69671\" style=\"width: 690px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"69671\" data-permalink=\"https:\/\/www.hoymercedes.com.ar\/principal\/2017\/11\/14\/quilmes-se-quedo-con-el-primero-de-los-clasicos-por-el-quinto-puesto\/whatsapp-image-2017-11-12-at-20-26-16\/#main\" data-orig-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2017\/11\/WhatsApp-Image-2017-11-12-at-20.26.16.jpeg\" data-orig-size=\"700,393\" data-comments-opened=\"0\" data-image-title=\"WhatsApp Image 2017-11-12 at 20.26.16\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Quilmes se qued\u00f3 con el primer encuentro ante Estudiantes.&lt;\/p&gt;\n\" data-large-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2017\/11\/WhatsApp-Image-2017-11-12-at-20.26.16.jpeg\" class=\"size-full wp-image-69671\" src=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2017\/11\/WhatsApp-Image-2017-11-12-at-20.26.16.jpeg\" alt=\"\" width=\"700\" height=\"393\" srcset=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2017\/11\/WhatsApp-Image-2017-11-12-at-20.26.16.jpeg 700w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2017\/11\/WhatsApp-Image-2017-11-12-at-20.26.16-150x84.jpeg 150w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2017\/11\/WhatsApp-Image-2017-11-12-at-20.26.16-630x354.jpeg 630w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><figcaption id=\"caption-attachment-69671\" class=\"wp-caption-text\">Quilmes se qued\u00f3 con el primer encuentro ante Estudiantes.<\/figcaption><\/figure>\n<p>De la mano de las penetraciones de Lara y buenos tiros externos de Parodi y Mandaglio, Estudiantes vivi\u00f3 su buen momento del partido en ese per\u00edodo. Quilmes, por su parte, no encontraba la manera efectiva de parar los ataques del pincha.<\/p>\n<p>En el ST, y ya con la conducci\u00f3n en la base de Valent\u00edn Mustoni, Quilmes recompuso su buen juego de ataque y defendi\u00f3 mucho mejor, ejerciendo f\u00e9rrea marca Manganiello sobre Lara. As\u00ed, quien logr\u00f3 un gran nivel en todo el partido, Pablo Juarez, convirti\u00f3 de varias maneras (dobles, triples, penetraciones, libres) qued\u00e1ndose con el premio de la figura del partido y siendo el goleador del mismo con 26 puntos. No se qued\u00f3 atr\u00e1s \u201cTito\u201d Mc Cormack con 23 puntos para lograr una buena ventaja final de 12 puntos. Ahora, la revancha ser\u00e1 el pr\u00f3ximo Viernes, siendo Estudiantes local y en caso de tercer partido, Quilmes jugar\u00e1 de local por haber estado mejor en la zona regular.<\/p>\n<p><strong>QUILMES 76:<\/strong>\u00a0Juarez 26, Mc Cormack 23, Mustoni 8, Manganiello 7, S. Cejas 6, R. Colicigno 4, N. Bozzini 2, Perdomo, Bonafina, M. Maldonado, Zumpano, Cosentino. <strong>DT:<\/strong> J. L. Giallorenzo<\/p>\n<p><strong>ESTUDIANTES 64:<\/strong>\u00a0Lara 20, Parodi 12, Perazzo 10, Crevani 9, Mandaglio 7, J. Siri 6, Parisso, Piers. <strong>DT:<\/strong> H. Mid\u00fan<\/p>\n<p><strong>PARCIALES:<\/strong> (19-20) (12-14) (27-16) (18-14)<\/p>\n<p><strong>JUECES:<\/strong> D atri &#8211; Guzm\u00e1n<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quilmes gan\u00f3 el cl\u00e1sico ante Estudiantes poniendo la serie 1 a 0 en la Copa de Plata. En un partido &#8230; <a title=\"Quilmes se qued\u00f3 con el primero de los cl\u00e1sicos por el quinto puesto\" class=\"read-more\" href=\"https:\/\/www.hoymercedes.com.ar\/principal\/2017\/11\/14\/quilmes-se-quedo-con-el-primero-de-los-clasicos-por-el-quinto-puesto\/\" aria-label=\"Leer m\u00e1s sobre Quilmes se qued\u00f3 con el primero de los cl\u00e1sicos por el quinto puesto\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":69671,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[21],"tags":[8513,204,10,1413],"class_list":["post-69668","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes","tag-basquet-de-primera","tag-deportes-2","tag-mercedes","tag-quilmes","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"jetpack_publicize_connections":[],"wps_subtitle":"Basquet de Primera","jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2017\/11\/WhatsApp-Image-2017-11-12-at-20.26.16.jpeg","_links":{"self":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/69668","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/comments?post=69668"}],"version-history":[{"count":0,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/69668\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media\/69671"}],"wp:attachment":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media?parent=69668"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/categories?post=69668"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/tags?post=69668"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}