{"id":70150,"date":"2017-11-28T11:58:34","date_gmt":"2017-11-28T14:58:34","guid":{"rendered":"http:\/\/www.hoymercedes.com.ar\/principal\/?p=70150"},"modified":"2017-11-27T21:55:46","modified_gmt":"2017-11-28T00:55:46","slug":"emanuel-bernal-y-marcos-mazzocchi-gritaron-campeon","status":"publish","type":"post","link":"https:\/\/www.hoymercedes.com.ar\/principal\/2017\/11\/28\/emanuel-bernal-y-marcos-mazzocchi-gritaron-campeon\/","title":{"rendered":"Emanuel Bernal y Marcos Mazzocchi gritaron campe\u00f3n"},"content":{"rendered":"<div>Otro de los tenistas mercedinos que contin\u00faa creciendo es Emanuel Bernal. Este Incansable trabajador se consagr\u00f3 campe\u00f3n del \u00faltimo Nacional de Grado 4 que finaliz\u00f3 ayer en las canchas del Club Din\u00e1mica de Luj\u00e1n sumando as\u00ed importantes puntos para seguir escalando en el r\u00e1nking argentino de menores.<\/div>\n<div><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"70151\" data-permalink=\"https:\/\/www.hoymercedes.com.ar\/principal\/2017\/11\/28\/emanuel-bernal-y-marcos-mazzocchi-gritaron-campeon\/img-20171126-wa0054\/#main\" data-orig-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2017\/11\/IMG-20171126-WA0054.jpg\" data-orig-size=\"581,1032\" data-comments-opened=\"0\" data-image-title=\"IMG-20171126-WA0054\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2017\/11\/IMG-20171126-WA0054-576x1024.jpg\" class=\"aligncenter size-full wp-image-70151\" src=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2017\/11\/IMG-20171126-WA0054.jpg\" alt=\"\" width=\"581\" height=\"1032\" srcset=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2017\/11\/IMG-20171126-WA0054.jpg 581w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2017\/11\/IMG-20171126-WA0054-84x150.jpg 84w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2017\/11\/IMG-20171126-WA0054-349x620.jpg 349w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2017\/11\/IMG-20171126-WA0054-576x1024.jpg 576w\" sizes=\"auto, (max-width: 581px) 100vw, 581px\" \/><\/div>\n<div><\/div>\n<div>El joven jugador alumno de los profesores Mauricio Pisoni y Hern\u00e1n Ricaldoni venci\u00f3 en la clasificaci\u00f3n a Pietro Liguori (6\/0-6\/1) y a Rodrigo Lewener (6\/0-6\/0) el s\u00e1bado, mientras que ayer se impuso en semifinales a M\u00e1ximo S\u00e1nchez por un contundente 6\/0-6\/1. La final fue contra un jugador de La Matanza: Luciano Rodr\u00edguez a qui\u00e9n venci\u00f3 en un muy duro pero emotivo 3\/6-6\/4-6\/1 consagratorio.<\/div>\n<div><\/div>\n<div><em><strong>Marcos Mazzocchi, campe\u00f3n<\/strong><\/em><\/div>\n<div><\/div>\n<div>\n<div>Y adem\u00e1s tuvimos en la ma\u00f1ana del s\u00e1bado el \u00faltimo torneo para la categor\u00eda \u00abD\u00bb del Calendario anual de internos para las escuelas del Club Mercedes y de la Liga de Padres que dirigenlos profesores Mauricio Pisoni y Hern\u00e1n Ricaldoni.<\/div>\n<\/div>\n<div><\/div>\n<div><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"70152\" data-permalink=\"https:\/\/www.hoymercedes.com.ar\/principal\/2017\/11\/28\/emanuel-bernal-y-marcos-mazzocchi-gritaron-campeon\/img-20171126-wa0017\/#main\" data-orig-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2017\/11\/IMG-20171126-WA0017.jpg\" data-orig-size=\"780,1040\" data-comments-opened=\"0\" data-image-title=\"IMG-20171126-WA0017\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2017\/11\/IMG-20171126-WA0017-768x1024.jpg\" class=\"aligncenter size-full wp-image-70152\" src=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2017\/11\/IMG-20171126-WA0017.jpg\" alt=\"\" width=\"780\" height=\"1040\" srcset=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2017\/11\/IMG-20171126-WA0017.jpg 780w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2017\/11\/IMG-20171126-WA0017-113x150.jpg 113w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2017\/11\/IMG-20171126-WA0017-465x620.jpg 465w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2017\/11\/IMG-20171126-WA0017-768x1024.jpg 768w\" sizes=\"auto, (max-width: 780px) 100vw, 780px\" \/><\/div>\n<div>\n<div>En las canchas de la Liga de Padres se coron\u00f3 campe\u00f3n Marcos Masiocchi al vencer en la final a Sim\u00f3n Quiroga en un gran partido. Felicitaciones a todos los ni\u00f1os que participaron, gran conducta y compa\u00f1erismo entre todos!! Organizado por los profesores Juan Manuel Regueiro y Emiliano Marcelo los ni\u00f1os fueron divididos en zonas jugando todos contra todos clasificando los dos mejores al cuadro final. Los resultados fueron los siguientes:<\/div>\n<div><\/div>\n<div><\/div>\n<div><strong>Zona I<\/strong><br \/>\n1- Tobias Buscalia<br \/>\n2- Antonio Bugallo<br \/>\n3- Thiago del Castillo<br \/>\n4- Dante Villafa\u00f1e<\/p>\n<p><strong>Zona II<\/strong><br \/>\n1- Simon Quiroga<br \/>\n2- Matias Rebagliati<br \/>\n3- Agust\u00edn Lombardo<br \/>\n4- Santi Cardinal<\/p>\n<p><strong>Zona III<\/strong><br \/>\n1- Marcos Massiochi<br \/>\n2- Santiago Cagnone<br \/>\n3- Felipe Rivero<br \/>\n4- Tobias Risso<\/p>\n<p>Los mejores primeros pasan directamente a semifinales<\/p>\n<p>Cuartos<br \/>\nAntonio Bugallo a Mati Rebagliati 15-10<\/p>\n<p>Simon Quiroga a Santiago Cagnone 15-11<\/p>\n<p>Semis<br \/>\nMarcos Massiochi a Antonio Bugallo 15-10<\/p>\n<p>Sim\u00f3n Quiroga a Tobias Buscalia 15-11<\/p>\n<p>Final<br \/>\nMarcos Massiochi a Sim\u00f3n Quiroga 15-13<\/p><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Otro de los tenistas mercedinos que contin\u00faa creciendo es Emanuel Bernal. Este Incansable trabajador se consagr\u00f3 campe\u00f3n del \u00faltimo Nacional &#8230; <a title=\"Emanuel Bernal y Marcos Mazzocchi gritaron campe\u00f3n\" class=\"read-more\" href=\"https:\/\/www.hoymercedes.com.ar\/principal\/2017\/11\/28\/emanuel-bernal-y-marcos-mazzocchi-gritaron-campeon\/\" aria-label=\"Leer m\u00e1s sobre Emanuel Bernal y Marcos Mazzocchi gritaron campe\u00f3n\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":70151,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[21],"tags":[204,12307,12308,6924],"class_list":["post-70150","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes","tag-deportes-2","tag-emanuel-bernal","tag-marcos-mazzochi","tag-tenis","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2017\/11\/IMG-20171126-WA0054.jpg","wps_subtitle":"Tenis","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/70150","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/comments?post=70150"}],"version-history":[{"count":0,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/70150\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media\/70151"}],"wp:attachment":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media?parent=70150"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/categories?post=70150"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/tags?post=70150"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}