{"id":70984,"date":"2017-12-20T12:44:58","date_gmt":"2017-12-20T15:44:58","guid":{"rendered":"http:\/\/www.hoymercedes.com.ar\/principal\/?p=70984"},"modified":"2017-12-20T11:00:09","modified_gmt":"2017-12-20T14:00:09","slug":"la-sade-mercedes-entrega-premios-a-la-literatura-2017","status":"publish","type":"post","link":"https:\/\/www.hoymercedes.com.ar\/principal\/2017\/12\/20\/la-sade-mercedes-entrega-premios-a-la-literatura-2017\/","title":{"rendered":"La SADE Mercedes entrega premios a la literatura 2017"},"content":{"rendered":"<p>Desde la Sociedad Argentina de Escritores Mercedes informaron que este viernes 22 de diciembre se entregar\u00e1n los premios del certamen literario \u00abRoberto J. Payr\u00f3\u00bb. A partir de la hora 17, en el sal\u00f3n de fiestas de calle 31, casi 20, dar\u00e1n los premios a autores nacionales y internacionales.<\/p>\n<p>Los cuatro primeros premios en los g\u00e9neros Poes\u00eda, Narrativa y Literatura Infantil (ambos g\u00e9neros) corresponden a: Alfredo Arie Rossi (Santa Fe); Stella Maris Demergasso (Lobos); Carlos Luj\u00e1n D\u00c1ndrea (Villa Urquiza) y \u00a0Alba Orieta (Bah\u00eda Blanca).<\/p>\n<p>Asimismo, los mercedinos que se encuentran entre los otros 23 premiados son: Germ\u00e1n Faure; Nadia Quevedo; Eduardo Marcelo Fal; Mar\u00eda Bel\u00e9n Gimenez.<\/p>\n<p>En total participaron 309 obras literarias.<\/p>\n<p>Por otra parte, en la ciudad de Buenos Aires se entregar\u00e1n los premios internacionales \u00abJos\u00e9 Hern\u00e1ndez\u00bb. En esta acto se distinguir\u00e1 a los docentes y alumnos de la\u00a0EEST N\u00b02 de Gowland por su participaci\u00f3n en la Suelta Nacional de Poemas que realiz\u00f3 SADE en la plaza San Mart\u00edn durante el d\u00eda nacional del Escritor.<\/p>\n<p>Adem\u00e1s se otorgar\u00e1n dos premios a dos novelistas de SADE Mercedes: Daiana Congett (La Fraternidad) y Bruno Z\u00e1rate (Mercedes).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desde la Sociedad Argentina de Escritores Mercedes informaron que este viernes 22 de diciembre se entregar\u00e1n los premios del certamen &#8230; <a title=\"La SADE Mercedes entrega premios a la literatura 2017\" class=\"read-more\" href=\"https:\/\/www.hoymercedes.com.ar\/principal\/2017\/12\/20\/la-sade-mercedes-entrega-premios-a-la-literatura-2017\/\" aria-label=\"Leer m\u00e1s sobre La SADE Mercedes entrega premios a la literatura 2017\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":70985,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[104],"tags":[7805,565,5148],"class_list":["post-70984","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura","tag-cultura","tag-premios","tag-sade-mercedes","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2017\/12\/20-Premios-SADE-Mercedes-2017.jpg","wps_subtitle":"Este viernes","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/70984","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/comments?post=70984"}],"version-history":[{"count":0,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/70984\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media\/70985"}],"wp:attachment":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media?parent=70984"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/categories?post=70984"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/tags?post=70984"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}