{"id":73441,"date":"2018-03-13T15:37:44","date_gmt":"2018-03-13T18:37:44","guid":{"rendered":"http:\/\/www.hoymercedes.com.ar\/principal\/?p=73441"},"modified":"2018-03-13T15:37:44","modified_gmt":"2018-03-13T18:37:44","slug":"el-concejal-biagini-denuncia-la-utilizacion-de-su-nombre-para-busqueda-laboral-falsa","status":"publish","type":"post","link":"https:\/\/www.hoymercedes.com.ar\/principal\/2018\/03\/13\/el-concejal-biagini-denuncia-la-utilizacion-de-su-nombre-para-busqueda-laboral-falsa\/","title":{"rendered":"El concejal Biagini denuncia la utilizaci\u00f3n de su nombre para b\u00fasqueda laboral falsa"},"content":{"rendered":"<p><em><strong>El concejal de Cambiemos Esteban Biagini hizo p\u00fablica una denuncia ante la utilizaci\u00f3n de un nombre hom\u00f3nimo al suyo y a la juventud del espacio pol\u00edtico convocando una b\u00fasqueda laboral ap\u00f3crifa. \u00a0\u201cAlertamos y advertimos ante la comunidad que esto es una mentira\u201d, destac\u00f3 el joven referente de la Juventud Radical.<\/strong><\/em><\/p>\n<figure id=\"attachment_73434\" aria-describedby=\"caption-attachment-73434\" style=\"width: 620px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"73434\" data-permalink=\"https:\/\/www.hoymercedes.com.ar\/principal\/2018\/03\/13\/selva-diserto-en-la-mesa-de-cooperacion-del-grupo-parlamentario-de-amistad-con-mexico\/13-cambiemos-biagini\/#main\" data-orig-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2018\/03\/13-cambiemos-Biagini.jpg\" data-orig-size=\"750,500\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"13 cambiemos Biagini\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Imagen de una convocatoria falsa que puede verse en las redes&lt;\/p&gt;\n\" data-large-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2018\/03\/13-cambiemos-Biagini.jpg\" class=\"size-medium wp-image-73434\" src=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2018\/03\/13-cambiemos-Biagini-630x420.jpg\" alt=\"\" width=\"630\" height=\"420\" srcset=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2018\/03\/13-cambiemos-Biagini-630x420.jpg 630w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2018\/03\/13-cambiemos-Biagini-150x100.jpg 150w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2018\/03\/13-cambiemos-Biagini.jpg 750w\" sizes=\"auto, (max-width: 630px) 100vw, 630px\" \/><figcaption id=\"caption-attachment-73434\" class=\"wp-caption-text\">Imagen de una convocatoria falsa que puede verse en las redes<\/figcaption><\/figure>\n<p>En la redes sociales est\u00e1 circulando una \u201cb\u00fasqueda laboral\u201d para oficinas del gobierno nacional con el sello y firma de la juventud de Cambiemos Mercedes con una direcci\u00f3n de correo electr\u00f3nico ajena a la utilizada por el frente pol\u00edtico local. A la respuesta del env\u00edo del curriculum vitae, el nombre que aparece como respuesta es \u201cEsteban Viagini\u201d (nombre hom\u00f3nimo al del Concejal Esteban Biagini).<\/p>\n<p>\u201cEsta semana sali\u00f3 una convocatoria a trav\u00e9s de las redes sociales, espec\u00edficamente en Facebook, en nombre de los j\u00f3venes de Cambiemos. Una convocatoria laboral para distintas reparticiones del Estado en Capital Federal. Ah\u00ed se pide que se env\u00ede el curriculum a una direcci\u00f3n de correo electr\u00f3nico. Me informaron que la respuesta de ese correo llega con un nombre similar al m\u00edo. Con mi nombre y el apellido escrito con \u2018V\u2019 en vez de con \u2018B\u2019. Esto podr\u00eda dar a entender que el que toma los curriculum soy yo y no es as\u00ed\u201d, explica el Concejal de Cambiemos Esteban Biagini,<\/p>\n<p>El joven concejal, tambi\u00e9n referente de la Juventud Radical, habl\u00f3 ante los medios para aclarar que desde la Juventud de Cambiemos no hab\u00eda salido esa convocatoria. E incluso el correo citado en la publicaci\u00f3n no pertenece a la direcci\u00f3n de contacto que Cambiemos tiene o tuvo alguna vez.<\/p>\n<p>\u201cAlertamos y advertimos ante la comunidad que esto es una mentira. Juegan con la ilusi\u00f3n de la gente que busca trabajo, confunden. \u00a0Quiero aclarar que no solamente es una falacia sino que tambi\u00e9n hay una clara mala intenci\u00f3n. Utilizan nombres e identidades que no son ver\u00eddicas. Este mensaje se hizo viral en las redes sociales. Es por esto que repudiamos este hecho de cobard\u00eda\u201d, agreg\u00f3 Biagini que en oportunidades anteriores hicieron una denuncia ante la red social por perfiles falsos utilizando sus nombres, sabiendo que ante la justicia la denuncia no prospera ante la falta de normativa en cuanto a redes sociales de \u00edndole internacional.<\/p>\n<p>M\u00e1s all\u00e1 de la explicaci\u00f3n que brinda el concejal del Frente Cambiemos, este hecho recuerda otras \u201cb\u00fasquedas laborales\u201d ap\u00f3crifas que generan ilusi\u00f3n en las personas que necesitan trabajar. Cabe recordar la \u201cconvocatoria\u201d realizada hace casi dos a\u00f1os para \u201cuna cadena de hamburgueser\u00eda\u201d que tuvo que salir a desmentir no s\u00f3lo la b\u00fasqueda laboral local sino la instalaci\u00f3n en la ciudad de una franquicia.<\/p>\n<p>La preocupaci\u00f3n y el resguardo que tienen que tener quienes env\u00edan estos curriculum a una direcci\u00f3n de correo electr\u00f3nico respondiendo a una convocatoria falsa es qu\u00e9 sucede con los datos que uno completa y env\u00eda en ese mail.<\/p>\n<p>Por Clarisa Altieri<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El concejal de Cambiemos Esteban Biagini hizo p\u00fablica una denuncia ante la utilizaci\u00f3n de un nombre hom\u00f3nimo al suyo y &#8230; <a title=\"El concejal Biagini denuncia la utilizaci\u00f3n de su nombre para b\u00fasqueda laboral falsa\" class=\"read-more\" href=\"https:\/\/www.hoymercedes.com.ar\/principal\/2018\/03\/13\/el-concejal-biagini-denuncia-la-utilizacion-de-su-nombre-para-busqueda-laboral-falsa\/\" aria-label=\"Leer m\u00e1s sobre El concejal Biagini denuncia la utilizaci\u00f3n de su nombre para b\u00fasqueda laboral falsa\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":73434,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[5],"tags":[7033,6011,7492,10,5319],"class_list":["post-73441","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-denuncia","tag-esteban-biagini","tag-frente-cambiemos","tag-mercedes","tag-politica-2","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2018\/03\/13-cambiemos-Biagini.jpg","wps_subtitle":"Difusi\u00f3n a trav\u00e9s de redes sociales","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/73441","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/comments?post=73441"}],"version-history":[{"count":0,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/73441\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media\/73434"}],"wp:attachment":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media?parent=73441"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/categories?post=73441"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/tags?post=73441"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}