{"id":760,"date":"2010-12-02T04:50:24","date_gmt":"2010-12-02T04:50:24","guid":{"rendered":"http:\/\/www.hoymercedes.com.ar\/principal\/?p=760"},"modified":"2010-12-04T00:14:18","modified_gmt":"2010-12-04T00:14:18","slug":"el-aumento-en-el-alumbrado-publico-llegaria-al-30-por-ciento","status":"publish","type":"post","link":"https:\/\/www.hoymercedes.com.ar\/principal\/2010\/12\/02\/el-aumento-en-el-alumbrado-publico-llegaria-al-30-por-ciento\/","title":{"rendered":"El aumento en el Alumbrado P\u00fablico llegar\u00eda al 30 por ciento"},"content":{"rendered":"<p style=\"text-align: justify;\">El Concejo Deliberante se reuni\u00f3 de manera extraordinaria para dar tratamiento a la solicitud de ingreso a dicho Cuerpo para su an\u00e1lisis y posterior aprobaci\u00f3n del proyecto de Ordenanza General Fiscal e Impositiva que como se sabe es la que regula los valores de ls tasas que el Municipio percibe por la prestaci\u00f3n de los diferentes servicios y por los distintos derechos que le corresponden de acuerdo a lo establecido en la Ley Org\u00e1nica de las Municipalidades.<\/p>\n<p style=\"text-align: justify;\">Desde hace algunas semanas tanto el intendente Carlos Selva como el Secretario de Econom\u00eda contador Rodolfo Berardo expresaron que necesariamente se deb\u00eda realizar un reajuste en ciertas tasas ya que a pesar del esfuerzo que se hace en materia de cobrabilidad son sumamente deficitarias.<\/p>\n<p style=\"text-align: justify;\">Por su parte el presidente del bloque de Concejales del Justicialismo, Marcelo Denapole confirm\u00f3\u00a0 que la tasa en la que m\u00e1s se notar\u00e1 el ireajuste que se producir\u00e1\u00a0 es la de Alumbrado, barrido y Limpieza que es una de las m\u00e1s deficitaria a apesar que con el sistema de percepci\u00f3n de los montos correspondiente al alumbrado p\u00fablico se hace a trav\u00e9s de la facturaci\u00f3n domiciliaria y comercial de la empresa EDEN SA, los montos fijados no alcanzan a cubir el gasto que origina tener el alumbrado nocturno.<\/p>\n<p style=\"text-align: justify;\">Den\u00e1pole estimo que el porcentaje de aumento estar\u00eda en el orden del 30 por ciento en los sectores que cuentan con una mayor cantidad de luminarias, mientras que en zonas m\u00e1s alejadas del centro el aumento podr\u00eda estar en alrededor del 20 por ciento.<\/p>\n<p style=\"text-align: justify;\">Posteriormente el concejal oficialista sostuvo que la otra tasa que sufrir\u00e1 modificaciones teniendo en cuenta el costo de los insumos que en necesitan para poder cumplir con la misma es la de Conservaci\u00f3n de la Red Vial, es decir todo lo concerniente a los caminos y calles rurales cuyo aumento oscilar\u00e1 el orden del veinte por ciento.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Posteriormente agreg\u00f3\u00a0 \u201ces voluntad del intendente tratar de no aumentar m\u00e1s que esas dos tasas porque realmente son altamente deficitaria a pesar que como ya lo hemos dicho en la parte de alumbrado p\u00fablico el porcentaje de incobrabilidad pr\u00e1cticamente es nulo, por lo tanto el resto de los grav\u00e1menes permanecer\u00e1n como hasta el momento y eso se puede hacer debido a que para el 2011 se ha estimado un fuerte incremento en la coparticipaci\u00f3n desde el gobierno de la provincia lo cual hace que se puedan equilibrar perfectamente las cuentas\u201d<\/p>\n<p style=\"text-align: justify;\">La idea generalizada dentro del concejo es tratar el proyecto que hoy entrar\u00e1 formalmente en los pr\u00f3ximos d\u00edas para que en lo posible junto con la propuesta de Ordenanza del Presupuesto este aprobada antes del 20 del mes venidero.<\/p>\n<p style=\"text-align: justify;\">Para aprobar a Ordenanza Impositiva primero deber\u00e1 realizarse una sesi\u00f3n preparatoria y posteriormente la Asamblea de Concejales y Mayores Contribuyentes.<\/p>\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>El Concejo Deliberante se reuni\u00f3 de manera extraordinaria para dar tratamiento a la solicitud de ingreso a dicho Cuerpo para &#8230; <a title=\"El aumento en el Alumbrado P\u00fablico llegar\u00eda al 30 por ciento\" class=\"read-more\" href=\"https:\/\/www.hoymercedes.com.ar\/principal\/2010\/12\/02\/el-aumento-en-el-alumbrado-publico-llegaria-al-30-por-ciento\/\" aria-label=\"Leer m\u00e1s sobre El aumento en el Alumbrado P\u00fablico llegar\u00eda al 30 por ciento\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[30],"tags":[214],"class_list":["post-760","post","type-post","status-publish","format-standard","hentry","category-municipio","tag-aumento-impuestos","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","wps_subtitle":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/760","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/comments?post=760"}],"version-history":[{"count":0,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/760\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media?parent=760"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/categories?post=760"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/tags?post=760"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}