{"id":79779,"date":"2018-08-15T07:43:11","date_gmt":"2018-08-15T10:43:11","guid":{"rendered":"http:\/\/www.hoymercedes.com.ar\/principal\/?p=79779"},"modified":"2018-08-14T17:42:58","modified_gmt":"2018-08-14T20:42:58","slug":"importante-victoria-de-quilmes-en-u13-en-saladillo","status":"publish","type":"post","link":"https:\/\/www.hoymercedes.com.ar\/principal\/2018\/08\/15\/importante-victoria-de-quilmes-en-u13-en-saladillo\/","title":{"rendered":"Importante victoria de Quilmes en U13 en Saladillo"},"content":{"rendered":"<p>En la 2\u00ba fecha del Clausura de las formativas de la ABCH, la categor\u00eda U 13 del cervecero logr\u00f3 una excelente victoria en dif\u00edcil reducto de Saladillo. Las dem\u00e1s categor\u00edas fueron derrotadas.<\/p>\n<p>&nbsp;<\/p>\n<p>FECHA 2: CANCHA \u201cJACOBO URSO\u201d (SALADILLO)<\/p>\n<p>&nbsp;<\/p>\n<p>MINI<\/p>\n<p>&nbsp;<\/p>\n<p>En la m\u00e1s chica de las categor\u00edas Quilmes cay\u00f3 derrotado por 41 a 30. Un partido que arranc\u00f3 parejo pero que tuvo un quiebre a favor del local en el segundo cuarto: lo gan\u00f3 por 10 a 1 y esa diferencia fue irremontable para Quilmes y termin\u00f3 en derrota ante un equipo al que se venci\u00f3 claramente en final four del torneo anterior. En el local sobresali\u00f3 Tom\u00e1s Delia con 10 puntos y en Quilmes Juan Bourdieu con 17 puntos (goleador del partido).<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>CIUDAD DE SALADILLO 41<\/p>\n<p>(T. Delia\u00a0 (C) 10, G. Mazza 7, Garc\u00eda Gadda 7, F. Nissi 6, Filgueiras 6, Leonardi 2, Cui\u00f1as 2, A. Sivero 1, Grune, Hernaez, Reynoso, F. Grassi) (DT: G. Molina)<\/p>\n<p>&nbsp;<\/p>\n<p>QUILMES 30<\/p>\n<p>(Bourdieu (C) 17, Milesi 5, Basualdo 4, Avelar 2, Almir\u00f3n 2, \u00a0Br\u00eda , Nasso , Silva , Gal\u00e1n , F. Cosentino , \u00a0Acu\u00f1a, \u00a0Ramponi, V. Bongiorno) \u00a0(DT: G. Retegui)<\/p>\n<p>&nbsp;<\/p>\n<p>GOLEADORES QUILMES: CAMPEONATO:<\/p>\n<p>Bourdieu\u00a0 29, Basualdo 12,\u00a0 Br\u00eda 10,\u00a0 Nasso 6, Milesi 5<\/p>\n<p>&nbsp;<\/p>\n<p>U13<\/p>\n<p>&nbsp;<\/p>\n<p>La alegr\u00eda del d\u00eda para el quilme\u00f1o: gran victoria en esta categor\u00eda con una gran actuaci\u00f3n de Juan Bourdieu con 26 puntos y el buen acompa\u00f1amiento general de todo el equipo y en particular de Thiago Bongiorno (9 puntos) y de \u201cJoaco\u201d \u00a0Cabanas (8). Esta categor\u00eda hilvan\u00f3, hasta ahora, dos victorias importantes que lo hacen creer en lograr el campeonato. Le gan\u00f3 a Racing con el cual hab\u00eda perdido en el campeonato anterior y ahora lo hace en Saladillo.<\/p>\n<p>&nbsp;<\/p>\n<p>CIUDAD DE SALADILLO 41<\/p>\n<p>(Mussi Manzoor (C) 17, T. Segura 10, T. Delia\u00a0 8, Campagnucci 3, England 2, M\u00edguez 1,\u00a0 Garc\u00eda Gadda, Leonardi, A. Dolcee, Balverde) (DT: G. Molina)<\/p>\n<p>&nbsp;<\/p>\n<p>QUILMES\u00a0 53<\/p>\n<p>(Bourdieu 26, T. Bongiorno 9, \u00a0J. Cabanas (C) 8, Gal\u00e1n 2, Verd\u00f3n 2, Portessi 2, Bonfiglio 2, Ayesa 2, \u00a0I. Alvarez, Cend\u00e1n, T. Torres, Almir\u00f3n) (DT: G. Retegui)<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>GOLEADORES QUILMES: CAMPEONATO<\/p>\n<p>Bourdieu 47 , J. Cabanas 26, T. Bongiorno 12 , Bonfiglio 8 , I. Alvarez 7<\/p>\n<p>&nbsp;<\/p>\n<p>U15<\/p>\n<p>&nbsp;<\/p>\n<p>La victoria se escap\u00f3 de las manos. Quilmes hizo pr\u00e1cticamente todo en el partido. \u00a0Lo bueno y lo malo. Lo perd\u00eda por pocos puntos, lo pas\u00f3 a ganar por 7 y luego, tras excesos de individualismo y yerros incre\u00edbles, lo termin\u00f3 perdiendo por 10. Ven\u00eda de lograr 3 victorias consecutivas\u00a0 ante el mismo rival y lo ven\u00eda logrando nuevamente y c\u00f3modamente. Ten\u00eda, \u00a0incluso, dominado psicol\u00f3gicamente el partido. Realiz\u00f3 un excelente segundo cuarto (17 a 5), pero declin\u00f3 sobre todo en los\u00a0 cuartos finales\u00a0 (19- 11 y 20-11 abajo) lo que hizo que de ganar por 7 se pasara a perder finalmente por 10: 61 a 51. En el local fueron destacados Blas Idoeta (21 puntos) y Salvador Nissi (16). En Quilmes lo m\u00e1s regular y valioso fue lo realizado por Emilio Carcagno.<\/p>\n<p>&nbsp;<\/p>\n<p>CIUDAD DE SALADILLO 61<\/p>\n<p>(B. Idoeta 21, S. Nissi (C) 16, T. Dolcee 8, Mengoni 6, Molfino 5, Alba 5, M. Arlego, V. Sivero, Garraham, V. Medrano, Pace, Pucciarelli) (DT: O. Debiase)<\/p>\n<p>&nbsp;<\/p>\n<p>QUILMES 51<\/p>\n<p>(Beyer 11, Carcagno 8, \u00a0Graziadei (C) 7, Bernardo 7, Tassara 5,\u00a0 Quinteros 4,\u00a0 Cabana 4, Lencioni 3,\u00a0 Brovelli 2, Aveiro, Indurain, J. Cabanas) (DT: G. Retegui)<\/p>\n<p>&nbsp;<\/p>\n<p>GOLEADORES QUILMES: CAMPEONATO<\/p>\n<p>Beyer 26, Lencioni 17, Tassara 17, Graziadei\u00a0 17, Carcagno 13<\/p>\n<p>&nbsp;<\/p>\n<p>U 17<\/p>\n<p>&nbsp;<\/p>\n<p>Claras diferencias marc\u00f3 un potencial campe\u00f3n como Ciudad de Saladillo (con la ausencia de su jugador estrella Santiago Mazza) y un esforzado equipo de Quilmes que ocup\u00f3 el sexto puesto final en el Apertura. Se vieron desde el inicio con muy buenas actuaciones de Ignacio Savone, Blas Idoeta, Gabrieloni y los hermanos Segura. Incontrolables para el conjunto cervecero y sacando diferencias a medida que pasaban los cuartos. En Quilmes gran cuarto final de \u201cTomy\u201d Bal (17 puntos totales) y de Bernardo Loch.<\/p>\n<p>&nbsp;<\/p>\n<p>CIUDAD DE SALADILLO 72<\/p>\n<p>(Savone 13, B. Idoeta 12, Gabrieloni 11, I. Segura 8, Grassi 7, Fuillerat 6, F. Sivero 6, N. Segura (C) 5, Samperio 4,\u00a0 S. Nissi, Hansen, Storti) (DT: O. Debiase)<\/p>\n<p>&nbsp;<\/p>\n<p>QUILMES 42<\/p>\n<p>(Bal (C) 17, Loch 8, F. Contardi 7, Carcagno\u00a0 6, Festugatto 2, Beyer 2,\u00a0 Fredes, Valiente, Graziadei,\u00a0 Tassara, Lencioni, Pomerantz) (DT: G. Retegui)<\/p>\n<p>&nbsp;<\/p>\n<p>GOLEADORES QUILMES: CAMPEONATO:<\/p>\n<p>&nbsp;<\/p>\n<p>Bal 17, Loch 8, F. Contardi 7, Carcagno\u00a0 6<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>JUECES: F. Tenaglia \u2013 A. Guzm\u00e1n<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>DESTACADO DEL D\u00cdA: JUAN BOURDIEU (MINI \/ U13)<\/p>\n<p>Los 17 puntos en Mini (a pesar de la derrota) y los 26 en U13 (determinante en la \u00fanica victoria del d\u00eda) marcaron la gran jornada de Juan que lo termin\u00f3, como si esto fuera poco, entrenando con la Selecci\u00f3n U13 en Chivilcoy, prepar\u00e1ndose para la eliminatoria zonal ante Jun\u00edn. Lo hace, pr\u00e1cticamente, s\u00e1bado a s\u00e1bado lo que hace que no sorprenda este nivel. Pero cuando se le agrega esta victoria de visitante en tan dif\u00edcil cancha es m\u00e1s loable todav\u00eda. Felicitaciones para Juan y ojal\u00e1 que estos rendimientos notables lo coronen, junto a sus compa\u00f1eros, en el logro del campeonato.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>PR\u00d3XIMA FECHA: 3\u00ba (25\/8\/18): \u00a0\u00a0Col\u00f3n (Ch) &#8211; Quilmes<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En la 2\u00ba fecha del Clausura de las formativas de la ABCH, la categor\u00eda U 13 del cervecero logr\u00f3 una &#8230; <a title=\"Importante victoria de Quilmes en U13 en Saladillo\" class=\"read-more\" href=\"https:\/\/www.hoymercedes.com.ar\/principal\/2018\/08\/15\/importante-victoria-de-quilmes-en-u13-en-saladillo\/\" aria-label=\"Leer m\u00e1s sobre Importante victoria de Quilmes en U13 en Saladillo\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[21],"tags":[11301,204,1413,11057],"class_list":["post-79779","post","type-post","status-publish","format-standard","hentry","category-deportes","tag-basquet-inferiores","tag-deportes-2","tag-quilmes","tag-saladillo","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","wps_subtitle":"Basquet Inferiores","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/79779","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/comments?post=79779"}],"version-history":[{"count":0,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/79779\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media?parent=79779"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/categories?post=79779"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/tags?post=79779"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}