{"id":83628,"date":"2018-11-08T10:24:58","date_gmt":"2018-11-08T13:24:58","guid":{"rendered":"http:\/\/www.hoymercedes.com.ar\/principal\/?p=83628"},"modified":"2018-11-07T22:52:32","modified_gmt":"2018-11-08T01:52:32","slug":"estudiantes-vencio-a-carmen-de-areco-y-es-finalista-en-primera-division","status":"publish","type":"post","link":"https:\/\/www.hoymercedes.com.ar\/principal\/2018\/11\/08\/estudiantes-vencio-a-carmen-de-areco-y-es-finalista-en-primera-division\/","title":{"rendered":"Estudiantes venci\u00f3 a Carmen de Areco y es finalista en Primera Divisi\u00f3n"},"content":{"rendered":"<p>El domingo se jugaron las finales de Primera Divisi\u00f3n del torneo de la Liga del Noroeste de B\u00e1squet Amateur, donde Estudiantes busca volver a ser campe\u00f3n en Primera Divisi\u00f3n luego de que le arrebataran el campeonato en 2017. En semifinales, tras clasificar en la segunda posici\u00f3n, enfrent\u00f3 en su cancha al CEF de Carmen de Areco a quien venci\u00f3 56 a 33. Ahora jugar\u00e1 la final con Sportivo Dorrego de Navarro, como local. El celeste elimin\u00f3 a Independiente de Capit\u00e1n Sarmiento.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"83629\" data-permalink=\"https:\/\/www.hoymercedes.com.ar\/principal\/2018\/11\/08\/estudiantes-vencio-a-carmen-de-areco-y-es-finalista-en-primera-division\/estudiantes-primera-basquet-2-2\/#main\" data-orig-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2018\/11\/Estudiantes-Primera-Basquet-2.jpg\" data-orig-size=\"960,720\" data-comments-opened=\"0\" data-image-title=\"Estudiantes Primera Basquet 2\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2018\/11\/Estudiantes-Primera-Basquet-2.jpg\" class=\"size-medium wp-image-83629 aligncenter\" src=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2018\/11\/Estudiantes-Primera-Basquet-2-630x473.jpg\" alt=\"\" width=\"630\" height=\"473\" srcset=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2018\/11\/Estudiantes-Primera-Basquet-2-630x473.jpg 630w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2018\/11\/Estudiantes-Primera-Basquet-2-150x113.jpg 150w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2018\/11\/Estudiantes-Primera-Basquet-2.jpg 960w\" sizes=\"auto, (max-width: 630px) 100vw, 630px\" \/><\/p>\n<p>Desde el principio el equipo dirigido por Lucas Tessore comenz\u00f3 jugando bien, sacando en forma r\u00e1pida una diferencia en el marcador que lo hizo finalizar el primer cuarto por 18 a 10 para sacar una diferencia de 17 puntos al finalizar el primer tiempo.<\/p>\n<p>Con buen juego y muy buena defensa jug\u00f3 el primer tiempo, luego, en el segundo la historia fue m\u00e1s pareja, pero siempre con el Pincha tranquilo, para quedar empatados 9 a 9 en el tercer cuarto y 13 a 7 en el tramo final. Buena conducci\u00f3n de Franco Mandaglio, Sebasti\u00e1n Zunino Sampablo aportando goleo y Gast\u00f3n Colicigno baj\u00f3 una buena cantidad de rebotes.<\/p>\n<p>Estudiantes form\u00f3 con Sebasti\u00e1n Zunino Sampablo, Franco Mandaglio, Robledo, Guido Parodi, Niciforo, S\u00e1nchez, Rodrigo Colicigno, Mendias, Jorge Siri, Hugo Satrustegui, Pablo Utemur.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El domingo se jugaron las finales de Primera Divisi\u00f3n del torneo de la Liga del Noroeste de B\u00e1squet Amateur, donde &#8230; <a title=\"Estudiantes venci\u00f3 a Carmen de Areco y es finalista en Primera Divisi\u00f3n\" class=\"read-more\" href=\"https:\/\/www.hoymercedes.com.ar\/principal\/2018\/11\/08\/estudiantes-vencio-a-carmen-de-areco-y-es-finalista-en-primera-division\/\" aria-label=\"Leer m\u00e1s sobre Estudiantes venci\u00f3 a Carmen de Areco y es finalista en Primera Divisi\u00f3n\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":83629,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[21],"tags":[13995,204,829],"class_list":["post-83628","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes","tag-basqeute-amateur","tag-deportes-2","tag-estudiantes","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"jetpack_publicize_connections":[],"wps_subtitle":"Basquet Amateur","jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2018\/11\/Estudiantes-Primera-Basquet-2.jpg","_links":{"self":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/83628","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/comments?post=83628"}],"version-history":[{"count":0,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/83628\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media\/83629"}],"wp:attachment":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media?parent=83628"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/categories?post=83628"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/tags?post=83628"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}