{"id":85390,"date":"2018-12-11T21:48:05","date_gmt":"2018-12-12T00:48:05","guid":{"rendered":"http:\/\/www.hoymercedes.com.ar\/principal\/?p=85390"},"modified":"2018-12-13T08:21:31","modified_gmt":"2018-12-13T11:21:31","slug":"%ef%bb%bfustarroz-firmo-nuevo-aporte-para-obras-del-municipio-al-queridohonguito","status":"publish","type":"post","link":"https:\/\/www.hoymercedes.com.ar\/principal\/2018\/12\/11\/%ef%bb%bfustarroz-firmo-nuevo-aporte-para-obras-del-municipio-al-queridohonguito\/","title":{"rendered":"\ufeffUstarroz firm\u00f3 nuevo aporte para obras del Municipio al Honguito"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><br><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"985\" height=\"657\" data-attachment-id=\"85391\" data-permalink=\"https:\/\/www.hoymercedes.com.ar\/principal\/2018\/12\/11\/%ef%bb%bfustarroz-firmo-nuevo-aporte-para-obras-del-municipio-al-queridohonguito\/dsc_0008-3\/#main\" data-orig-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2018\/12\/DSC_0008.jpg\" data-orig-size=\"985,657\" data-comments-opened=\"0\" data-image-title=\"Ustarroz-Rudoni-Silva\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2018\/12\/DSC_0008.jpg\" src=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2018\/12\/DSC_0008.jpg\" alt=\"\" class=\"wp-image-85391\" srcset=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2018\/12\/DSC_0008.jpg 985w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2018\/12\/DSC_0008-150x100.jpg 150w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2018\/12\/DSC_0008-630x420.jpg 630w\" sizes=\"auto, (max-width: 985px) 100vw, 985px\" \/><figcaption>Jorgelina Silva, Juan Ustarroz y Pocha Rudoni\u00a0<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Mediante la decisi\u00f3n del\nintendente Juan Ignacio Ustarroz, y a trav\u00e9s de la Secretar\u00eda de Desarrollo\nsocial, se le dar\u00e1 soluci\u00f3n a una problem\u00e1tica que afecta de manera directa el\nnormal funcionamiento del Honguito. Esta reconocida instituci\u00f3n alberga y ayuda\na 49 ni\u00f1os de nuestra ciudad. Tras el pedido y posterior verificaci\u00f3n, que\nparte de la ca\u00f1er\u00eda estaba totalmente destruida, el Municipio de Mercedes -con\nfondos propios- otorg\u00f3 la suma total de 160 mil pesos. Con este monto se prev\u00e9\nse solvente el total de la obra. \u201cUna alegr\u00eda muy grande poder seguir\nacompa\u00f1ando y apoyando al Honguito, una instituci\u00f3n muy querida por la\ncomunidad\u201d expres\u00f3 el jefe comunal. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por otro lado, el intendente\nUstarroz dijo \u201csiempre recuerdo cuando \u201cpocha\u201d nos dec\u00eda que estaban\ncomplicados y todo apuntaba a su cierre en el a\u00f1o 2016, por lo aumentos\ndesmedidos de los servicios y gastos en general, y por aquel entonces les\ndijimos que cuenten con el Municipio\u201d. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A su vez, indic\u00f3 \u201cno solamente el\nHonguito no cerr\u00f3, sino que adem\u00e1s, viene progresando mucho. Se realiz\u00f3 una\nsalita nueva, parte de este emblem\u00e1tico lugar se est\u00e1 remodelando y\nrefaccionando, y para nosotros poder hacer este aporte es muy importante\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En cuanto a la ayuda que se le\nbrindar\u00e1 para la soluci\u00f3n que acaece a nivel estructural el edificio, el Dr.\nUstarroz sostuvo \u201choy le estamos otorgando 160 mil pesos que ser\u00e1 administrado\npor la instituci\u00f3n, y que permitir\u00e1 un avance de obra muy significativo\u201d y\nasegur\u00f3 \u201cse est\u00e1 aportando en algo central, que es la infraestructura\u201d. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Conjuntamente, el jefe comunal\nvalor\u00f3 de manera rotunda la labor que desarrollan todos los que integran el\nestablecimiento \u201cdespu\u00e9s est\u00e1 el d\u00eda a d\u00eda, lo que hace y seguir\u00e1 haciendo\ngrande al Honguito, que es el recurso humano, la valoraci\u00f3n que tiene el vecino\ny las familias sobre esta querida instituci\u00f3n\u201d y remarc\u00f3 \u201cpara nosotros es una\nprioridad, porque algo central en lo que trabaja la gesti\u00f3n, son los ni\u00f1os\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es importante destacar que el\nMunicipio, junto a la Secretar\u00eda de Desarrollo Social se est\u00e1 colaborando de\nmanera permanente con esta instituci\u00f3n. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cPocha\u201d Rudoni, una de las\npersonas que impulsa y sostiene el emblem\u00e1tico jard\u00edn El Honguito de nuestra\nciudad cont\u00f3 \u201cfuimos visitados por los arquitectos de la municipalidad, quienes\nvinieron a comprobar el estado de la salita inaugurada por el municipio, y\nencontraron que las ca\u00f1er\u00edas de agua estaban obstruidas\u201d y agreg\u00f3 \u201cnos dijeron\nse hab\u00eda derrumbado el ca\u00f1o y por ese motivo no desagotaba\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fue as\u00ed como desde el Municipio\nse envi\u00f3 un grupo de trabajo, que determin\u00f3 que las ca\u00f1er\u00edas, debido al\ndesgaste y el tiempo de uso, se encontraban obsoletas \u201ces tan grande la\ndestrucci\u00f3n -una casa que data de m\u00e1s de 30 a\u00f1os- que la ca\u00f1er\u00eda ya no existe,\nse derrumbaron los ca\u00f1os\u201d indic\u00f3 Pocha.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por este motivo, desde lainstituci\u00f3n se pidi\u00f3 la ayuda al municipio para la soluci\u00f3n de este problema,que de seguir, conllevar\u00eda serios problemas estructurales al edificio. Es as\u00ed comoRudoni valor\u00f3 \u201cexiste muy buena disposici\u00f3n y una impronta, desde el Municipiode Mercedes, de hacer las cosas bien\u201d.<\/p>\n\n\n\n<p class=\"has-text-color has-cyan-bluish-gray-color wp-block-paragraph\">Data: Sec. Desarrollo Social<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mediante la decisi\u00f3n del intendente Juan Ignacio Ustarroz, y a trav\u00e9s de la Secretar\u00eda de Desarrollo social, se le dar\u00e1 &#8230; <a title=\"\ufeffUstarroz firm\u00f3 nuevo aporte para obras del Municipio al Honguito\" class=\"read-more\" href=\"https:\/\/www.hoymercedes.com.ar\/principal\/2018\/12\/11\/%ef%bb%bfustarroz-firmo-nuevo-aporte-para-obras-del-municipio-al-queridohonguito\/\" aria-label=\"Leer m\u00e1s sobre \ufeffUstarroz firm\u00f3 nuevo aporte para obras del Municipio al Honguito\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":85391,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[30],"tags":[10589,244,12157],"class_list":["post-85390","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-municipio","tag-el-honguito","tag-municipio-2","tag-pocha-rudoni","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2018\/12\/DSC_0008.jpg","wps_subtitle":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/85390","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/comments?post=85390"}],"version-history":[{"count":0,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/85390\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media\/85391"}],"wp:attachment":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media?parent=85390"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/categories?post=85390"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/tags?post=85390"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}