{"id":91338,"date":"2019-04-15T09:22:58","date_gmt":"2019-04-15T12:22:58","guid":{"rendered":"http:\/\/www.hoymercedes.com.ar\/principal\/?p=91338"},"modified":"2019-04-15T10:03:29","modified_gmt":"2019-04-15T13:03:29","slug":"carlos-selva-de-recorrida-por-25-de-mayo","status":"publish","type":"post","link":"https:\/\/www.hoymercedes.com.ar\/principal\/2019\/04\/15\/carlos-selva-de-recorrida-por-25-de-mayo\/","title":{"rendered":"Carlos Selva de recorrida por 25 de Mayo"},"content":{"rendered":"\n<p>D\u00edas atr\u00e1s, el diputado nacional Carlos Selva fue parte de una visita junto a varios de sus pares a la localidad de 25 de Mayo, para apoyar al referente local Diego Di Salvo, quien brind\u00f3 una charla acompa\u00f1ado por los Diputados Nacionales del Frente Renovador Jos\u00e9 Ignacio de Mendiguren, Cecilia Moreau, Marcela Passo y el propio Selva.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"563\" data-attachment-id=\"91342\" data-permalink=\"https:\/\/www.hoymercedes.com.ar\/principal\/2019\/04\/15\/carlos-selva-de-recorrida-por-25-de-mayo\/13-selva-de-gira-2\/#main\" data-orig-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/04\/13-selva-de-gira-2.jpg\" data-orig-size=\"750,563\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"13 selva de gira 2\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/04\/13-selva-de-gira-2.jpg\" src=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/04\/13-selva-de-gira-2.jpg\" alt=\"\" class=\"wp-image-91342\" srcset=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/04\/13-selva-de-gira-2.jpg 750w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/04\/13-selva-de-gira-2-150x113.jpg 150w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/04\/13-selva-de-gira-2-630x473.jpg 630w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/04\/13-selva-de-gira-2-320x240.jpg 320w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/04\/13-selva-de-gira-2-100x75.jpg 100w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/figure>\n\n\n\n<p>A la hora de decir unas palabras ante los medios, Selva agradeci\u00f3 a Di Salvo por su invitaci\u00f3n a la ciudad de 25 de Mayo. \u201cHay un camino que estamos recorriendo y nos motiva predisponernos a escuchar inquietudes. Hay un debate de c\u00f3mo se desarrolla la pol\u00edtica y estamos convencidos de que Sergio Massa tiene que conducir este espacio porque tiene una mirada federal muy afianzada en como tienen que ser tomados los municipios. Nosotros creemos que el federalismo se construye fortaleciendo los municipios la autonom\u00eda y el crecimiento de los municipios es nuestro objetivo y debe estar en la agenda pol\u00edtica\u201d, dijo Selva, quien tiene tres mandatos en su ciudad de Mercedes.<\/p>\n\n\n\n<p>\u201cLos municipios deben estar conectados con los vecinos, y hay temas que se construyen desde abajo hacia arriba como el medio ambiente y el equilibrio del Estado\u201d, dijo luego y sostuvo que hay cuestiones como las tarifas y los desechos cloacales que trabajar de este modo. \u201cEl ciudadano tiene que implicarse, debe haber un marco normativo\u201d, opin\u00f3 Selva.<\/p>\n\n\n\n<p>\u201cNosotros tenemos equipos trabajando y debemos discutir como se solucionan los problemas de la Argentina, mas all\u00e1 de quienes sean los candidatos. El pr\u00f3ximo gobierno debe trabajar sobre ciertos ejes\u201d, dijo.<\/p>\n\n\n\n<p>Por \u00faltimo, Selva destac\u00f3 la valent\u00eda del referente local Diego Di Salvo de ponerse a trabajar en su candidatura por 25 de Mayo, dejando tiempo dedicado a su famlia y otros aspectos. \u201cTiene ganas de asumir responsabilidades y la posibilidad de demostrar que se consolida la coherencia de un proyecto nacional, provincial y municipal\u201d, explic\u00f3.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" data-attachment-id=\"91341\" data-permalink=\"https:\/\/www.hoymercedes.com.ar\/principal\/2019\/04\/15\/carlos-selva-de-recorrida-por-25-de-mayo\/13-selva-de-gira-1\/#main\" data-orig-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/04\/13-selva-de-gira-1.jpg\" data-orig-size=\"800,533\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"13 selva de gira 1\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/04\/13-selva-de-gira-1.jpg\" src=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/04\/13-selva-de-gira-1.jpg\" alt=\"\" class=\"wp-image-91341\" srcset=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/04\/13-selva-de-gira-1.jpg 800w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/04\/13-selva-de-gira-1-150x100.jpg 150w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/04\/13-selva-de-gira-1-630x420.jpg 630w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/04\/13-selva-de-gira-1-720x480.jpg 720w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/04\/13-selva-de-gira-1-360x240.jpg 360w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>D\u00edas atr\u00e1s, el diputado nacional Carlos Selva fue parte de una visita junto a varios de sus pares a la &#8230; <a title=\"Carlos Selva de recorrida por 25 de Mayo\" class=\"read-more\" href=\"https:\/\/www.hoymercedes.com.ar\/principal\/2019\/04\/15\/carlos-selva-de-recorrida-por-25-de-mayo\/\" aria-label=\"Leer m\u00e1s sobre Carlos Selva de recorrida por 25 de Mayo\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":91341,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[5210],"tags":[39,10113],"class_list":["post-91338","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica-nacional","tag-carlos-selva","tag-politica-nacional","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/04\/13-selva-de-gira-1.jpg","wps_subtitle":"Acompa\u00f1ando a candidatos","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/91338","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/comments?post=91338"}],"version-history":[{"count":0,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/91338\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media\/91341"}],"wp:attachment":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media?parent=91338"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/categories?post=91338"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/tags?post=91338"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}