{"id":94361,"date":"2019-06-03T20:55:21","date_gmt":"2019-06-03T23:55:21","guid":{"rendered":"http:\/\/www.hoymercedes.com.ar\/principal\/?p=94361"},"modified":"2019-06-03T20:57:57","modified_gmt":"2019-06-03T23:57:57","slug":"inauguran-la-primera-cancha-de-torball-de-mercedes-y-la-segunda-del-pais","status":"publish","type":"post","link":"https:\/\/www.hoymercedes.com.ar\/principal\/2019\/06\/03\/inauguran-la-primera-cancha-de-torball-de-mercedes-y-la-segunda-del-pais\/","title":{"rendered":"Inauguran la primera cancha de Torball de Mercedes y la segunda del pa\u00eds"},"content":{"rendered":"\n<p>El jefe comunal inaugur\u00f3 una nueva cancha de Torball en Mercedes. Es la segunda del pa\u00eds. Se encuentra en dependencias de la Direcci\u00f3n de Deportes. Ya hubo competencias y la satisfacci\u00f3n del avance en la inclusi\u00f3n. Estuvo presente la Federaci\u00f3n Argentina de Deportes para Ciegos.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"741\" height=\"632\" data-attachment-id=\"94362\" data-permalink=\"https:\/\/www.hoymercedes.com.ar\/principal\/2019\/06\/03\/inauguran-la-primera-cancha-de-torball-de-mercedes-y-la-segunda-del-pais\/torball-5-1\/#main\" data-orig-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/06\/Torball.5-1.jpg\" data-orig-size=\"741,632\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Torball.5-1\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/06\/Torball.5-1.jpg\" src=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/06\/Torball.5-1.jpg\" alt=\"\" class=\"wp-image-94362\" srcset=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/06\/Torball.5-1.jpg 741w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/06\/Torball.5-1-150x128.jpg 150w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/06\/Torball.5-1-630x537.jpg 630w\" sizes=\"auto, (max-width: 741px) 100vw, 741px\" \/><\/figure>\n\n\n\n<p>La primera actividad cont\u00f3 con la participaci\u00f3n del equipo municipal de torball y un combinado de la FADEC.&nbsp;&nbsp;<\/p>\n\n\n\n<p>\u201cHoy es un gran d\u00eda, un paso muy importante para nuestra mirada del deporte en Mercedes, con la inclusi\u00f3n y todo lo que significa la actividad deportiva\u201d dijo Mart\u00edn Silvestre, director de deportes y sostuvo que \u201cestamos orgullosos de compartir este\u201d afirm\u00f3 ante los jugadores que disputaron luego un encuentro, familiares y amigos presentes.<\/p>\n\n\n\n<p>Por su parte, el intendente Ustarroz, afirm\u00f3 que \u201ces un orgullo enorme acompa\u00f1arlos, darles la bienvenida y poder en Mercedes tener esta cancha, este espacio y contar con personas valios\u00edsimas en las direcciones de deportes y discapacidad\u201d y afirm\u00f3 que \u201cqueremos una ciudad m\u00e1s inclusiva, para ello trabajan todas nuestras \u00e1reas, queremos una ciudad con justicia social y estas peque\u00f1as cosas nos llenan de alegr\u00edas\u201d narr\u00f3 y destac\u00f3 que \u201cpor eso es una emoci\u00f3n y orgullo enorme construir la segunda cancha a nivel pa\u00eds\u201d destac\u00f3 siendo un dato muy valioso.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"948\" height=\"632\" data-attachment-id=\"94363\" data-permalink=\"https:\/\/www.hoymercedes.com.ar\/principal\/2019\/06\/03\/inauguran-la-primera-cancha-de-torball-de-mercedes-y-la-segunda-del-pais\/torball-1\/#main\" data-orig-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/06\/Torball.-1.jpg\" data-orig-size=\"948,632\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Torball.-1\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/06\/Torball.-1.jpg\" src=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/06\/Torball.-1.jpg\" alt=\"\" class=\"wp-image-94363\" srcset=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/06\/Torball.-1.jpg 948w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/06\/Torball.-1-150x100.jpg 150w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/06\/Torball.-1-630x420.jpg 630w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/06\/Torball.-1-720x480.jpg 720w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/06\/Torball.-1-360x240.jpg 360w\" sizes=\"auto, (max-width: 948px) 100vw, 948px\" \/><\/figure>\n\n\n\n<p>M\u00e1s adelante dijo que \u201cuno de los principales objetivos que tenemos es el deporte con inclusi\u00f3n\u201d y remarc\u00f3 que \u201ces necesarios cada vez contar con m\u00e1s espacios inclusivos y los iremos generando, porque trabajamos todos unidos, es un d\u00eda muy feliz\u201d destac\u00f3.<\/p>\n\n\n\n<p>Por su parte, el representantes de la Federaci\u00f3n Argentina de Deportes para Ciegos, sostuvo que \u201cdesde toda la comisi\u00f3n directiva quer\u00edamos apoyar esta actividad\u201d narr\u00f3 y dijo que \u201chace mucho tiempo, recuerdo, un 1 de junio, recuerdo claramente, donde las personas con discapacidad est\u00e1bamos muy postergados, nos recibi\u00f3 el presidente N\u00e9stor Kirchner en la Casa Rosada y le pedimos nos d\u00e9 una mano y ah\u00ed empezamos a cambiar. Desde entonces siempre pedimos nos den una mano y hoy estamos muy agradecidos, orgullosos, por eso estar ac\u00e1 es una alegr\u00eda enorme\u201d, sostuvo N\u00e9stor Cirillo, integrante de la FADEC y referente de Ituzaing\u00f3 de deporte inclusivo.<\/p>\n\n\n\n<p>La Directora de Discapacidad, Tatiana L\u00f3pez, remarc\u00f3 que \u201cen Mercedes se viene haciendo un fuerte y s\u00f3lido trabajo en inclusi\u00f3n, con rampas, plazas, deportes, cursos, el CETIM y tantas otras medidas que perdurar\u00e1n en el tiempo, como esta cancha que usa el equipo municipal, pero tambi\u00e9n todos los que lo deseen, porque para nuestra gesti\u00f3n la inclusi\u00f3n es eje de trabajo de todos los d\u00edas\u201d.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"948\" height=\"632\" data-attachment-id=\"94364\" data-permalink=\"https:\/\/www.hoymercedes.com.ar\/principal\/2019\/06\/03\/inauguran-la-primera-cancha-de-torball-de-mercedes-y-la-segunda-del-pais\/torball-2-1\/#main\" data-orig-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/06\/Torball.2-1.jpg\" data-orig-size=\"948,632\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Torball.2-1\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/06\/Torball.2-1.jpg\" src=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/06\/Torball.2-1.jpg\" alt=\"\" class=\"wp-image-94364\" srcset=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/06\/Torball.2-1.jpg 948w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/06\/Torball.2-1-150x100.jpg 150w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/06\/Torball.2-1-630x420.jpg 630w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/06\/Torball.2-1-720x480.jpg 720w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/06\/Torball.2-1-360x240.jpg 360w\" sizes=\"auto, (max-width: 948px) 100vw, 948px\" \/><\/figure>\n\n\n\n<p>Estuvo tambi\u00e9n presente la coordinadora de deportes, Mariana Saboredo y personal de ambas direcciones mencionadas, siendo la jornada una \u201cfiesta\u201d, remarcaron, con entrega de plaqueta al municipio por parte de la FADEC reconociendo el \u201cgran paso dado en este d\u00eda\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El jefe comunal inaugur\u00f3 una nueva cancha de Torball en Mercedes. Es la segunda del pa\u00eds. Se encuentra en dependencias &#8230; <a title=\"Inauguran la primera cancha de Torball de Mercedes y la segunda del pa\u00eds\" class=\"read-more\" href=\"https:\/\/www.hoymercedes.com.ar\/principal\/2019\/06\/03\/inauguran-la-primera-cancha-de-torball-de-mercedes-y-la-segunda-del-pais\/\" aria-label=\"Leer m\u00e1s sobre Inauguran la primera cancha de Torball de Mercedes y la segunda del pa\u00eds\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":94362,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[21],"tags":[11059],"class_list":["post-94361","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes","tag-torball","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/06\/Torball.5-1.jpg","wps_subtitle":"Torball","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/94361","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/comments?post=94361"}],"version-history":[{"count":0,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/94361\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media\/94362"}],"wp:attachment":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media?parent=94361"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/categories?post=94361"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/tags?post=94361"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}