{"id":94675,"date":"2019-06-07T17:00:18","date_gmt":"2019-06-07T20:00:18","guid":{"rendered":"http:\/\/www.hoymercedes.com.ar\/principal\/?p=94675"},"modified":"2019-06-07T15:38:46","modified_gmt":"2019-06-07T18:38:46","slug":"la-asamblea-por-la-agroecologia-celebra-que-concejales-traten-la-ordenanza","status":"publish","type":"post","link":"https:\/\/www.hoymercedes.com.ar\/principal\/2019\/06\/07\/la-asamblea-por-la-agroecologia-celebra-que-concejales-traten-la-ordenanza\/","title":{"rendered":"La Asamblea por la Agroecolog\u00eda celebra que concejales traten la ordenanza"},"content":{"rendered":"\n<p>Desde la\u00a0Asamblea Mercedina por la Agroecolog\u00eda (AMA)\u00a0hay mucha expectativa ya que este lunes 10 de junio se tratar\u00e1 en el Concejo Deliberante el proyecto presentado por este grupo de una\u00a0Ordenanza de Fomento de la Agroecolog\u00eda\u00a0en sus m\u00faltiples formas. Durante todo el a\u00f1o pasado y parte del corriente, la AMA sostuvo una incesante iniciativa de debates y actividades tendientes a involucrar a actores del \u00e1mbito agrario y profesionales ligados al sector, con la intenci\u00f3n de enriquecer la elaboraci\u00f3n de la Ordenanza presentada.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"500\" data-attachment-id=\"94676\" data-permalink=\"https:\/\/www.hoymercedes.com.ar\/principal\/2019\/06\/07\/la-asamblea-por-la-agroecologia-celebra-que-concejales-traten-la-ordenanza\/07-asamblea-agro\/#main\" data-orig-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/06\/07-asamblea-agro.jpg\" data-orig-size=\"750,500\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"07 asamblea agro\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/06\/07-asamblea-agro.jpg\" src=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/06\/07-asamblea-agro.jpg\" alt=\"\" class=\"wp-image-94676\" srcset=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/06\/07-asamblea-agro.jpg 750w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/06\/07-asamblea-agro-150x100.jpg 150w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/06\/07-asamblea-agro-630x420.jpg 630w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/06\/07-asamblea-agro-720x480.jpg 720w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/06\/07-asamblea-agro-360x240.jpg 360w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/figure>\n\n\n\n<p>Construida con un esp\u00edritu participativo y democr\u00e1tico, y teniendo como principal objetivo el bienestar popular, la Ordenanza de la AMA apunta a incentivar la producci\u00f3n agroecol\u00f3gica en la ciudad. Pretende alentar cultivos que garanticen una alimentaci\u00f3n saludable (sin agroqu\u00edmicos t\u00f3xicos), basada en el respeto de los equilibrios ambientales (sustentable) y en el trabajo digno en el \u00e1mbito rural (dignidad laboral). Es decir, es una Ordenanza que apunta a introducir normativas cuyos valores impl\u00edcitos gozan de gran consenso social. Su estructura demanda un presupuesto acorde que le d\u00e9 viabilidad institucional; un Consejo ciudadano de co-gesti\u00f3n junto al Municipio de las Pol\u00edticas Agroecol\u00f3gicas; y un plan de acceso a la tierra para productores y trabajadores rurales sin acceso a ella.<\/p>\n\n\n\n<p>Por todo esto, la AMA invita a la comunidad en general a acompa\u00f1ar este proyecto, este lunes 10 de junio, a las 19 hs. al Palacio Municipal a presenciar el tratamiento de la Ordenanza.<\/p>\n\n\n\n<p>Fuente: prensa AMA<br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desde la\u00a0Asamblea Mercedina por la Agroecolog\u00eda (AMA)\u00a0hay mucha expectativa ya que este lunes 10 de junio se tratar\u00e1 en el &#8230; <a title=\"La Asamblea por la Agroecolog\u00eda celebra que concejales traten la ordenanza\" class=\"read-more\" href=\"https:\/\/www.hoymercedes.com.ar\/principal\/2019\/06\/07\/la-asamblea-por-la-agroecologia-celebra-que-concejales-traten-la-ordenanza\/\" aria-label=\"Leer m\u00e1s sobre La Asamblea por la Agroecolog\u00eda celebra que concejales traten la ordenanza\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":94676,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[8],"tags":[15213,8955,8979],"class_list":["post-94675","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sociedad","tag-asamblea-por-la-agroecologia","tag-proyecto-de-ordenanza","tag-sesion-hcd","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/06\/07-asamblea-agro.jpg","wps_subtitle":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/94675","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/comments?post=94675"}],"version-history":[{"count":0,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/94675\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media\/94676"}],"wp:attachment":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media?parent=94675"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/categories?post=94675"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/tags?post=94675"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}