{"id":97440,"date":"2019-08-01T09:19:10","date_gmt":"2019-08-01T12:19:10","guid":{"rendered":"http:\/\/www.hoymercedes.com.ar\/principal\/?p=97440"},"modified":"2019-07-31T21:23:07","modified_gmt":"2019-08-01T00:23:07","slug":"insisten-en-la-realizacion-de-la-red-de-agua-corriente-en-gowland-y-agote","status":"publish","type":"post","link":"https:\/\/www.hoymercedes.com.ar\/principal\/2019\/08\/01\/insisten-en-la-realizacion-de-la-red-de-agua-corriente-en-gowland-y-agote\/","title":{"rendered":"Insisten en la realizaci\u00f3n de la red de agua corriente en Gowland y Agote"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><em>Los concejales dirigen una petici\u00f3n para que organismo provincial para la concreci\u00f3n del proyecto. Por su parte, la concejal Laporta lamenta el retraso en la respuesta del Ejecutivo ante la consulta realizada inicialmente en 2017 y reiterada en el 2019 que informaba de un acuerdo de hace ocho a\u00f1os. <\/em><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"500\" data-attachment-id=\"97441\" data-permalink=\"https:\/\/www.hoymercedes.com.ar\/principal\/2019\/08\/01\/insisten-en-la-realizacion-de-la-red-de-agua-corriente-en-gowland-y-agote\/agua-gowland\/#main\" data-orig-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/07\/agua-gowland.jpg\" data-orig-size=\"750,500\" data-comments-opened=\"0\" data-image-title=\"agua-gowland\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/07\/agua-gowland.jpg\" src=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/07\/agua-gowland.jpg\" alt=\"Piden que se concrete la obra acordada en 2011 junto con el abastecimiento de agua de Tom\u00e1s Jofr\u00e9. \" class=\"wp-image-97441\" srcset=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/07\/agua-gowland.jpg 750w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/07\/agua-gowland-150x100.jpg 150w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/07\/agua-gowland-630x420.jpg 630w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/07\/agua-gowland-720x480.jpg 720w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/07\/agua-gowland-360x240.jpg 360w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">El servicio\nde agua corriente en la zona rural, es uno de los reclamos que los vecinos\nplantean en distintos \u00e1mbitos. Hace un par de a\u00f1os, el Concejo Deliberante\npresent\u00f3 una resoluci\u00f3n para que el Ejecutivo contemple la obra en presupuestos\nposteriores. El mismo pedido lo hizo este a\u00f1o y la respuesta sorprendi\u00f3 a los\nlegisladores ya que se informa que la obra en Gowland hab\u00eda sido licitada en\n2011 junto a la de Tom\u00e1s Jofr\u00e9, pero no concretada. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esto motiv\u00f3\na los Concejales al armado de una resoluci\u00f3n un\u00e1nime que ser\u00eda aprobada en la\nsesi\u00f3n del venidero 12 de agosto solicitando a SPAR la concreci\u00f3n de la obra\nque le lleve el servicio de agua corriente a Gowland y Agote. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEn 2017\npresentamos una consulta para hacer la red del agua corriente para Gowland y\nAgote. En 2019 volvimos a preguntar porque en aquella oportunidad no hab\u00eda\ntenido una respuesta concreta. Y ahora nos responden que el agua para Gowland\nse licit\u00f3 en 2011, con la de Tom\u00e1s Jofr\u00e9, y la provincia no la hizo en aquel\nmomento\u201d, expres\u00f3 la Concejal Laporta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;\u201cCuando veo la contestaci\u00f3n en la \u00faltima\nsesi\u00f3n solicito el retiro del expediente para la comisi\u00f3n porque ah\u00ed nos dicen\nque hubo un llamado a licitaci\u00f3n en 2011 pero que se concret\u00f3 solamente en\nTom\u00e1s Jofr\u00e9. Y refiere a un plan del 2016 solicitado. Me pregunto por qu\u00e9 no\nnos contestaron antes esto. As\u00ed pod\u00edamos avanzar antes y capaz que ya se\nhubiese resuelto. Nos contestaron dos a\u00f1os despu\u00e9s\u201d, enfatiz\u00f3 la legisladora. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el\ninforme firmado por el Jefe de Gobierno, Mat\u00edas Dematei, se asegura que la obra\nfue solicitada al SPAR (Servicio provincial de Agua Potable y Saneamiento\nRural) bajo el convenio rubricado entre el organismo municipal y el Municipio\nen el a\u00f1o 2011. En ese mismo acuerdo se estipulaba el predio donde se construir\u00eda\nel tanque de reserva y de la sala de comando, tal como el que est\u00e1 en Tom\u00e1s\nJofr\u00e9 \u201cpor el cual el SPAR desarroll\u00f3 el proyecto ejecutivo de la obra y su\ncorrespondiente llamado a licitaci\u00f3n p\u00fablica de la redes de agua en las\nlocalidades de T. Jofr\u00e9 y Gowland, concret\u00e1ndose solamente la ejecuci\u00f3n de la\nred en Tom\u00e1s Jofr\u00e9\u201d. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el mismo\ninforme se explicita que en el a\u00f1o 2016 se solicit\u00f3 la obra y su financiamiento\na la SubSecretar\u00eda de Recursos H\u00eddricos de Naci\u00f3n y a la Secretar\u00eda de Vivienda\ny H\u00e1bitat bajo el marco del Programa Promeba 3 y 4. Aunque no se informa si\nhubo alg\u00fan tipo de respuesta para,&nbsp;\nfinalmente, pedirle al Legislativo que \u201crefuerce\u201d los pedidos de la obra\nante el organismo provincial. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tras leer\nla respuesta, la Concejal Laporta insisti\u00f3: \u201cSi nos hubiesen respondido en el\n2017, hubi\u00e9semos ganado tiempo porque ahora nos pide que insistamos desde el\nHCD, para lo cual armamos un nuevo despacho\u201d. &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los\nconcejales que integran la Comisi\u00f3n de Obras P\u00fablicas, firmaron un despacho\npara consultar la situaci\u00f3n de ese expediente ante el organismo provincial. All\u00ed\nse pide al SPAR que informe \u201cel estado de concreci\u00f3n de la licitaci\u00f3n p\u00fablica\nefectuada de acuerdo al convenio firmado con el municipio de Mercedes para la\ndotaci\u00f3n de agua potable en las localidades de Gowland y Agote\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y agregan:\n\u201cContemplando extracci\u00f3n, tanque de almacenamiento, red de impulsi\u00f3n y la\ndistribuci\u00f3n tal cual fuera realizado por aplicaci\u00f3n de dicho convenio en la\nlocalidad de Tom\u00e1s Jofr\u00e9. Haciendo referencia adem\u00e1s que en el a\u00f1o 2011 el\nmunicipio de Mercedes puso a disposici\u00f3n del SPAR un predio de dominio\nmunicipal para la construcci\u00f3n del tanque de reserva y de la sala de comando\nubicado en calle 525 y 504 de 1541 m2 en Gowland\u201d<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los concejales dirigen una petici\u00f3n para que organismo provincial para la concreci\u00f3n del proyecto. Por su parte, la concejal Laporta &#8230; <a title=\"Insisten en la realizaci\u00f3n de la red de agua corriente en Gowland y Agote\" class=\"read-more\" href=\"https:\/\/www.hoymercedes.com.ar\/principal\/2019\/08\/01\/insisten-en-la-realizacion-de-la-red-de-agua-corriente-en-gowland-y-agote\/\" aria-label=\"Leer m\u00e1s sobre Insisten en la realizaci\u00f3n de la red de agua corriente en Gowland y Agote\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":74838,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[5],"tags":[874,236,15,5319,8980,8628],"class_list":["post-97440","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-agua-potable","tag-concejo-deliberante","tag-hcd","tag-politica-2","tag-proyectos","tag-servicios-publicos","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2018\/04\/20-pety-laporta.jpg","wps_subtitle":"Trabajo legislativo","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/97440","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/comments?post=97440"}],"version-history":[{"count":0,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/97440\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media\/74838"}],"wp:attachment":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media?parent=97440"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/categories?post=97440"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/tags?post=97440"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}