{"id":98660,"date":"2019-08-22T05:58:26","date_gmt":"2019-08-22T08:58:26","guid":{"rendered":"http:\/\/www.hoymercedes.com.ar\/principal\/?p=98660"},"modified":"2019-08-21T20:09:36","modified_gmt":"2019-08-21T23:09:36","slug":"como-mejorar-la-educacion-ambiental","status":"publish","type":"post","link":"https:\/\/www.hoymercedes.com.ar\/principal\/2019\/08\/22\/como-mejorar-la-educacion-ambiental\/","title":{"rendered":"Como mejorar la educaci\u00f3n ambiental"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"> Cristi\u00e1n Frers* &#8211; Desde siempre la especie humana\u00a0 interaccion\u00f3 con el medio y lo\u00a0 modific\u00f3: los problemas no son nuevos. Sin embargo, lo que nos \u00a0preocupa es la situaci\u00f3n actual, la aceleraci\u00f3n de esas modificaciones, su car\u00e1cter masivo y lo\u00a0 universal de sus consecuencias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los\nproblemas del ecosistema ya no aparecen como independientes unos de otros sino\nque constituyen elementos que se relacionan entre s\u00ed, configurando una realidad\ndiferente a la simple acumulaci\u00f3n de todos ellos. Por lo mismo, hoy en d\u00eda\npodemos hablar de algo m\u00e1s que de simples problemas en el entorno, pues nos\nenfrentamos a una aut\u00e9ntica crisis ambiental y la gravedad de la crisis se\nmanifiesta en su car\u00e1cter local y global.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La\nsoluci\u00f3n requiere de un profundo cambio cultural en nuestra sociedad. Comenzar\na valorar nuestros recursos naturales y &nbsp;las posibilidades de desarrollo,\nlo cual deber\u00eda ser una prioridad social.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La\nense\u00f1anza sobre este tema es un proceso que les permite a las personas\ninvestigar &nbsp;esas tem\u00e1ticas, involucrarse en la resoluci\u00f3n de problemas\nsustentables y tomar medidas para mejorarlos. Como resultado, los individuos\nalcanzar\u00edan un entendimiento m\u00e1s profundo y tendr\u00edan las herramientas para\ntomar decisiones &nbsp;responsables.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El movimiento <a>Viernes para el Futuro <\/a>fue iniciado por Greta Thunberg, la adolescente sueca que en agosto de 2018 decidi\u00f3 faltar a clase todos los viernes para ir a protestar ante la sede del Parlamento de su pa\u00eds, hasta que se adopten medidas m\u00e1s en\u00e9rgicas para combatir el cambio clim\u00e1tico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Su\niniciativa para concientizar sobre la crisis &nbsp;no tard\u00f3 en extenderse por\ntodo el mundo. M\u00e1s de un mill\u00f3n de j\u00f3venes de todo el mundo participaron el 24\nde mayo del 2019 en las huelgas escolares por el clima&nbsp; en el movimiento Viernes para el Futuro. Hubo\nmanifestaciones en m\u00e1s de cien pa\u00edses, entre ellos Alemania, Australia, Brasil,\nFilipinas, India, Jap\u00f3n, Nigeria, Pakist\u00e1n, Reino Unido y Uganda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La activista sueca, iniciadora\nde las huelgas estudiantiles mundiales que -desde 2018- buscan concientizar\nsobre el cambio clim\u00e1tico, se\u00f1al\u00f3 que ni ella ni su movimiento deber\u00edan asumir\neste tipo de cargas, pero que &nbsp;les ha tocado hacerlo por la inacci\u00f3n de\nlos adultos frente al clima.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dentro\nde esta estructura r\u00edgida, en Argentina y, a pesar de los cambios llevados a\ncabo en los Ministerios de Educaci\u00f3n, se sigue pensando que la problem\u00e1tica\nambiental es para un \u00e1rea determinada. De manera acorde, la estructura actual\nde la ense\u00f1anza en Argentina no siempre facilita el verdadero di\u00e1logo, que permita\nahondar la dificultad que atraviesa&nbsp; ese grupo de estudiantes, en esa\ncomunidad en particular y en los otros pa\u00edses. Se desvaloriza un contenido, sin\nimportar con qui\u00e9n ni en d\u00f3nde uno se encuentre. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En\nla escuela no se facilita esta relaci\u00f3n &nbsp;de di\u00e1logo, ni siquiera se\nreflexiona en las necesidades, desaf\u00edos o dificultades que encuentran los\ndocentes&nbsp; sobre este tema .&nbsp; Encontramos el mismo sesgo en el mantra\nde la educaci\u00f3n ambiental: \u201cPensar global, actuar local\u201d. Muchas veces, esta\npostura&nbsp; no visibiliza las necesidades, por no decir urgencias locales y\nregionales. Pensemos local: pintemos nuestra aldea y as\u00ed pintaremos el mundo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A\npesar de su motivaci\u00f3n y capacidad de iniciativa, los docentes argentinos <strong>no\ncuentan con la suficiente formaci\u00f3n<\/strong> para poder impartir determinados\nconceptos y temas relacionados con el medioambiente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es\nbueno impulsar propuestas como la de Mar\u00eda de los Milagros Cisterna, -maestra\nde dos escuelas urbanas en Carmen de Areco \u2013 Provincia de Buenos Aires,\n&nbsp;sobre RECICLADO en las escuelas, quien piensa que: \u201cDebido a una\ndeficiente cultura de preservaci\u00f3n del medio ambiente, que trasciende en\nnuestros alumnos, es necesario incentivar la creatividad para producir,\ntransformando los desechos con arte e ingenio en productos que se puedan volver\na usar. El proyecto busca incentivar la conciencia ecol\u00f3gica, el reciclaje de residuos\ns\u00f3lidos se considera una estrategia importante para contribuir al fortalecimiento\nde una cultura ambientalista y de ahorro\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es\npor esto que la ciudad de Carmen de Areco, como todas las dem\u00e1s, deber\u00edan\nimpulsar, a trav\u00e9s de sus instituciones, un programa de educaci\u00f3n ambiental,\ndirigido a ni\u00f1os y adolescentes para involucrarlos activamente en el\nconocimiento de su medio ambiente y en el manejo de sus recursos naturales. La\npropuesta, tendr\u00eda que entenderse como una acci\u00f3n complementaria a la formaci\u00f3n\neducativa en los colegios, dirigida a brindarles oportunidades de aprendizaje,\nque vinculen la experiencia cognitiva con la vivencial, a trav\u00e9s de pr\u00e1cticas\nen el campo, relacionadas con comunidades campesinas, excursiones y talleres de\nreflexi\u00f3n sobre la gesti\u00f3n de los recursos naturales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seguramente\nmuchas maestras y maestros como Cisterna intentar\u00e1n lo mismo en distintas\nescuelas del pa\u00eds, pero sin la asistencia oficial -pues es escasa o\npr\u00e1cticamente nula-. Esto se debe, principalmente, a la precaria importancia,\nque frecuentemente se da a la ense\u00f1anza, como efecto de un presupuesto bajo y\nla ausencia de un debate acerca de la calidad y ventajas de la instrucci\u00f3n\n&nbsp;impartida, &nbsp;motivo por el cual &nbsp;surgen activistas como Greta\nThunberg.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La\ncultura clim\u00e1tica no consiste, entonces, en una mera aplicaci\u00f3n de ajustes y\ncomplementos a los programas tradicionales pedag\u00f3gicos: se trata, m\u00e1s bien, de\nconvocar a nuevos enfoques, contenidos y m\u00e9todos, haciendo m\u00e1s flexibles las\ntradicionales estructuras de los sistemas educativos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">*Cristi\u00e1n Frers \u2013 T\u00e9cnico Superior en Gesti\u00f3n Ambiental y T\u00e9cnico Superior en Comunicaci\u00f3n Social (Periodista).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cristi\u00e1n Frers* &#8211; Desde siempre la especie humana\u00a0 interaccion\u00f3 con el medio y lo\u00a0 modific\u00f3: los problemas no son nuevos. &#8230; <a title=\"Como mejorar la educaci\u00f3n ambiental\" class=\"read-more\" href=\"https:\/\/www.hoymercedes.com.ar\/principal\/2019\/08\/22\/como-mejorar-la-educacion-ambiental\/\" aria-label=\"Leer m\u00e1s sobre Como mejorar la educaci\u00f3n ambiental\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":91602,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[1],"tags":[9001,47,8748],"class_list":["post-98660","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-opinion","tag-ambiente","tag-educacion-2","tag-opinion","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/04\/18-ambiente-educaci\u00f3n.jpg","wps_subtitle":"Propuesta","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/98660","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/comments?post=98660"}],"version-history":[{"count":0,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/98660\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media\/91602"}],"wp:attachment":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media?parent=98660"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/categories?post=98660"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/tags?post=98660"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}