{"id":98815,"date":"2019-08-24T17:57:03","date_gmt":"2019-08-24T20:57:03","guid":{"rendered":"http:\/\/www.hoymercedes.com.ar\/principal\/?p=98815"},"modified":"2019-08-24T12:34:09","modified_gmt":"2019-08-24T15:34:09","slug":"el-nivel-inicial-celebro-el-dia-del-nino-exponiendo-sus-derechos","status":"publish","type":"post","link":"https:\/\/www.hoymercedes.com.ar\/principal\/2019\/08\/24\/el-nivel-inicial-celebro-el-dia-del-nino-exponiendo-sus-derechos\/","title":{"rendered":"El nivel inicial celebr\u00f3 el D\u00eda del Ni\u00f1o exponiendo sus Derechos"},"content":{"rendered":"\n<p><em>Los jardines de infantes y maternales de gesti\u00f3n p\u00fablica y privada expusieron en la plaza San Mart\u00edn los trabajos realizados por los peque\u00f1os sobre los Derechos del Ni\u00f1o. El proyecto educativo distrital plantea el conocimiento de derechos y deberes de los m\u00e1s peque\u00f1os y de los adultos hacia los ni\u00f1os. <\/em><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" data-attachment-id=\"98802\" data-permalink=\"https:\/\/www.hoymercedes.com.ar\/principal\/2019\/08\/24\/abogados-comisiones-de-los-organos-de-la-colegiacion-reunidas-en-dos-dias-de-trabajo\/jardinesdeinfantes-8\/#main\" data-orig-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/08\/jardinesdeinfantes-8.jpg\" data-orig-size=\"800,600\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;2&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Moto G (5S) Plus&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1566555841&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.59&quot;,&quot;iso&quot;:&quot;1611&quot;,&quot;shutter_speed&quot;:&quot;0.00038971161340608&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"jardinesdeinfantes 8\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/08\/jardinesdeinfantes-8.jpg\" src=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/08\/jardinesdeinfantes-8.jpg\" alt=\"\" class=\"wp-image-98802\" srcset=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/08\/jardinesdeinfantes-8.jpg 800w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/08\/jardinesdeinfantes-8-150x113.jpg 150w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/08\/jardinesdeinfantes-8-630x473.jpg 630w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/08\/jardinesdeinfantes-8-320x240.jpg 320w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/08\/jardinesdeinfantes-8-100x75.jpg 100w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<p>Desde la\nma\u00f1ana temprano hasta mitad de la tarde, las comunidades educativas del nivel\ninicial tanto de gesti\u00f3n p\u00fablico como de gesti\u00f3n privada, llevaron una muestra\nconjunta en la Plaza San Mart\u00edn en donde las diferentes salas de los Jardines\nde Infantes expusieron los trabajos realizados sobre los Derechos del Ni\u00f1o en\nel mes que celebr\u00f3 el d\u00eda de los m\u00e1s peque\u00f1os. <\/p>\n\n\n\n<p>Mar\u00eda de la\nPaz Duhalde, inspectora de nivel inicial de gesti\u00f3n privada, y Alejandra\nMaisonavo, inspectora nivel inicial de gesti\u00f3n p\u00fablica, presidieron el acto\ninaugural de una jornada en la que las comunidades educativas de distintas\ninstituciones mostraron el trabajo realizado durante el mes de agosto. <\/p>\n\n\n\n<p>\u201cMostramos lo que se hace en los jardines de infantes todos los d\u00edas. Fue una experiencia maravillosa para los jardines poder juntarse y compartir porque la idea era aprender del otro y unificar el trabajo. Hace un mes que se viene trabajando. Por cada derecho, trabaj\u00f3 una instituci\u00f3n estatal y una privada. La idea era valorar los derechos del ni\u00f1o y que no se vulneren. Ese fue el sentido del proyecto\u201d, explicaron las inspectoras. <\/p>\n\n\n\n<div class=\"wp-block-jetpack-slideshow aligncenter\" data-effect=\"slide\"><div class=\"wp-block-jetpack-slideshow_container swiper-container\"><ul class=\"wp-block-jetpack-slideshow_swiper-wrapper swiper-wrapper\"><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"534\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-98803\" data-id=\"98803\" src=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/08\/jardinesdeinfantes-9.jpg\" srcset=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/08\/jardinesdeinfantes-9.jpg 800w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/08\/jardinesdeinfantes-9-150x100.jpg 150w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/08\/jardinesdeinfantes-9-630x421.jpg 630w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/08\/jardinesdeinfantes-9-720x480.jpg 720w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/08\/jardinesdeinfantes-9-360x240.jpg 360w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-98802\" data-id=\"98802\" src=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/08\/jardinesdeinfantes-8.jpg\" srcset=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/08\/jardinesdeinfantes-8.jpg 800w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/08\/jardinesdeinfantes-8-150x113.jpg 150w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/08\/jardinesdeinfantes-8-630x473.jpg 630w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/08\/jardinesdeinfantes-8-320x240.jpg 320w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/08\/jardinesdeinfantes-8-100x75.jpg 100w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-98801\" data-id=\"98801\" src=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/08\/jardinesdeinfantes-7.jpg\" srcset=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/08\/jardinesdeinfantes-7.jpg 800w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/08\/jardinesdeinfantes-7-150x113.jpg 150w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/08\/jardinesdeinfantes-7-630x473.jpg 630w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/08\/jardinesdeinfantes-7-320x240.jpg 320w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/08\/jardinesdeinfantes-7-100x75.jpg 100w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-98800\" data-id=\"98800\" src=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/08\/jardinesdeinfantes-6.jpg\" srcset=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/08\/jardinesdeinfantes-6.jpg 800w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/08\/jardinesdeinfantes-6-150x113.jpg 150w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/08\/jardinesdeinfantes-6-630x473.jpg 630w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/08\/jardinesdeinfantes-6-320x240.jpg 320w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/08\/jardinesdeinfantes-6-100x75.jpg 100w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"534\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-98799\" data-id=\"98799\" src=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/08\/jardinesdeinfantes-5.jpg\" srcset=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/08\/jardinesdeinfantes-5.jpg 800w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/08\/jardinesdeinfantes-5-150x100.jpg 150w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/08\/jardinesdeinfantes-5-630x421.jpg 630w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/08\/jardinesdeinfantes-5-720x480.jpg 720w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/08\/jardinesdeinfantes-5-360x240.jpg 360w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"534\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-98798\" data-id=\"98798\" src=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/08\/jardinesdeinfantes-4.jpg\" srcset=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/08\/jardinesdeinfantes-4.jpg 800w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/08\/jardinesdeinfantes-4-150x100.jpg 150w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/08\/jardinesdeinfantes-4-630x421.jpg 630w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/08\/jardinesdeinfantes-4-720x480.jpg 720w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/08\/jardinesdeinfantes-4-360x240.jpg 360w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"534\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-98797\" data-id=\"98797\" src=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/08\/jardinesdeinfantes-3.jpg\" srcset=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/08\/jardinesdeinfantes-3.jpg 800w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/08\/jardinesdeinfantes-3-150x100.jpg 150w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/08\/jardinesdeinfantes-3-630x421.jpg 630w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/08\/jardinesdeinfantes-3-720x480.jpg 720w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/08\/jardinesdeinfantes-3-360x240.jpg 360w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-98796\" data-id=\"98796\" src=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/08\/jardinesdeinfantes-2.jpg\" srcset=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/08\/jardinesdeinfantes-2.jpg 800w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/08\/jardinesdeinfantes-2-150x113.jpg 150w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/08\/jardinesdeinfantes-2-630x473.jpg 630w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/08\/jardinesdeinfantes-2-320x240.jpg 320w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/08\/jardinesdeinfantes-2-100x75.jpg 100w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"534\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-98795\" data-id=\"98795\" src=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/08\/jardinesdeinfantes-1.jpg\" srcset=\"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/08\/jardinesdeinfantes-1.jpg 800w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/08\/jardinesdeinfantes-1-150x100.jpg 150w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/08\/jardinesdeinfantes-1-630x421.jpg 630w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/08\/jardinesdeinfantes-1-720x480.jpg 720w, https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/08\/jardinesdeinfantes-1-360x240.jpg 360w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure><\/li><\/ul><a class=\"wp-block-jetpack-slideshow_button-prev swiper-button-prev swiper-button-white\" role=\"button\"><\/a><a class=\"wp-block-jetpack-slideshow_button-next swiper-button-next swiper-button-white\" role=\"button\"><\/a><a aria-label=\"Pause Slideshow\" class=\"wp-block-jetpack-slideshow_button-pause\" role=\"button\"><\/a><div class=\"wp-block-jetpack-slideshow_pagination swiper-pagination swiper-pagination-white\"><\/div><\/div><\/div>\n\n\n\n<p>\u201cNuestro\nproyecto invita a los ni\u00f1os y adolescentes a trabajar sobre temas relacionados\ncon sus derechos y deberes, con el fin de concientizarlos sobre ellos.\nAspiramos a despertar la conciencia individual, para poder luego establecer\nacciones sociales encauzadas a la participaci\u00f3n de los alumnos en temas que les\nata\u00f1en en su \u00e1mbito local y el intercambio telem\u00e1tico entre estudiantes y\ndocentes, que favorece el conocimiento de otras realidades, a la vez que se\nreconoce y revaloriza lo propio\u201d, dijeron ante los presentes, entre ellos, la\nJefa de Inspectores de la Regi\u00f3n X, Mariana Sarmiento. <\/p>\n\n\n\n<p>\u201cBuscamos\nuna participaci\u00f3n activa, juntos analizamos y confrontamos diferentes situaciones\ny realidades que generar\u00e1n un juicio cr\u00edtico. Esperamos que sea \u00e9ste un aporte\nvaledero para educar para la vida y construir as\u00ed ese mundo mejor en el estamos\nempe\u00f1ados\u201d, agregaron las Se\u00f1oritas Mar\u00eda de la Paz y Alejandra. <\/p>\n\n\n\n<p>Alrededor\nde la plaza principal de la ciudad se colocaron con puestos con los distintos\ntrabajos realizados por los m\u00e1s peque\u00f1os. En cada puesto pod\u00eda verse la\nrepresentaci\u00f3n de cada uno de los derecho del ni\u00f1o: a la igualdad, sin\ndistinci\u00f3n de raza, religi\u00f3n o nacionalidad; a tener un nombre; a tener una\nnacionalidad; a alimentaci\u00f3n saludable; a una vivienda digna; a atenci\u00f3n m\u00e9dica\nadecuada; a la educaci\u00f3n; a atenciones especiales para los ni\u00f1os y ni\u00f1as con\ndiscapacidad; a la comprensi\u00f3n y al amor por parte de su familia y la sociedad;\na jugar; a divertirse; a la atenci\u00f3n y a la ayuda preferencial en caso de\npeligro; a recibir educaci\u00f3n que fomente la solidaridad, la amistad, la\njusticia entre todo el mundo; a leer en cualquier lugar; a la ciencia y a disfrutar\nde los beneficios del progreso cient\u00edfico; a un medioambiente adecuado y\nsaludable; al agua; y al trabajo cuando sean adultos. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los jardines de infantes y maternales de gesti\u00f3n p\u00fablica y privada expusieron en la plaza San Mart\u00edn los trabajos realizados &#8230; <a title=\"El nivel inicial celebr\u00f3 el D\u00eda del Ni\u00f1o exponiendo sus Derechos\" class=\"read-more\" href=\"https:\/\/www.hoymercedes.com.ar\/principal\/2019\/08\/24\/el-nivel-inicial-celebro-el-dia-del-nino-exponiendo-sus-derechos\/\" aria-label=\"Leer m\u00e1s sobre El nivel inicial celebr\u00f3 el D\u00eda del Ni\u00f1o exponiendo sus Derechos\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":98795,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[23],"tags":[1174,47,336,10821],"class_list":["post-98815","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion","tag-dia-del-nino","tag-educacion-2","tag-jardin-de-infantes","tag-nivel-inicial","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-content\/uploads\/2019\/08\/jardinesdeinfantes-1.jpg","wps_subtitle":"Durante la jornada del viernes","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/98815","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/comments?post=98815"}],"version-history":[{"count":0,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/posts\/98815\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media\/98795"}],"wp:attachment":[{"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/media?parent=98815"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/categories?post=98815"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hoymercedes.com.ar\/principal\/wp-json\/wp\/v2\/tags?post=98815"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}